{"id":5151,"date":"2020-03-13T11:12:43","date_gmt":"2020-03-13T17:12:43","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/smo\/?p=5151"},"modified":"2020-03-13T11:12:43","modified_gmt":"2020-03-13T17:12:43","slug":"invita-smo-a-concurso-de-fotografia-sobre-resiliencia-y-autonomia-de-las-mujeres","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sm\/invita-smo-a-concurso-de-fotografia-sobre-resiliencia-y-autonomia-de-las-mujeres\/","title":{"rendered":"Invita SMO a concurso de fotograf\u00eda sobre \u201cResiliencia y autonom\u00eda de las mujeres\u201d"},"content":{"rendered":"<ul>\n<li>Ser\u00e1n premiadas tres ganadoras con 10 mil, 8 mil y 5 mil pesos adem\u00e1s de menciones honor\u00edficas con 2 mil pesos<\/li>\n<\/ul>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax. 12 de marzo de 2020<\/strong>. La Secretar\u00eda de las Mujeres de Oaxaca (SMO) invita a fot\u00f3grafas a la 1\u00aa Edici\u00f3n del Concurso de Fotograf\u00eda \u201cResiliencia y autonom\u00eda: la libertad de las mujeres\u201d, donde se busca que las profesionales y aficionadas de la lente expresen con im\u00e1genes los procesos de sanaci\u00f3n de sus linajes femeninos.<\/p>\n<p>De acuerdo con la respectiva convocatoria, podr\u00e1n participar mujeres oaxaque\u00f1as de nacimiento mayores de 18 a\u00f1os y que radiquen en la entidad, con una foto individual o una serie de hasta tres fotograf\u00edas, con el tema de la resiliencia y autonom\u00eda de las mujeres, y tomada en el \u00e1mbito estatal.<\/p>\n<p>Las im\u00e1genes pueden ser a color o en blanco y negro, producidas en 2018, 2019 o 2020 -se cotejar\u00e1 la fecha de creaci\u00f3n de la imagen con los metadatos-, mediante cualquier t\u00e9cnica: procesos antiguos, an\u00e1loga o digital e incluso con tel\u00e9fonos celulares.<\/p>\n<p>No se admite la manipulaci\u00f3n digital, es decir, aumentar o quitar elementos de la imagen. Las fotograf\u00edas deber\u00e1n ser de su autor\u00eda y que no hayan participado en otros concursos.<\/p>\n<p>Las im\u00e1genes participantes deber\u00e1n tener las siguientes caracter\u00edsticas t\u00e9cnicas: 5 mil pixeles por el lado m\u00e1s corto a 300 dpi (alta resoluci\u00f3n) y llevar el t\u00edtulo en el nombre del archivo.<\/p>\n<p>Deber\u00e1n ser enviadas o entregadas en las oficinas de la SMO ubicadas en la\u00a0<a href=\"https:\/\/www.google.com\/maps\/search\/calle+Escuela+Naval+Militar+221+colonia+Reforma?entry=gmail&amp;source=g\">calle Escuela Naval Militar 221 colonia Reforma<\/a>, en sobre cerrado, dirigido a la Unidad de Comunicaci\u00f3n Social, firmada con seud\u00f3nimo, en un CD con la o las im\u00e1genes participantes y datos de la concursante: nombre completo, seud\u00f3nimo, tel\u00e9fono de contacto.<\/p>\n<p>Asimismo, deber\u00e1 argumentar previamente la interpretaci\u00f3n del proceso resiliente del material enviado. La convocatoria queda abierta hasta el 17 de marzo.<\/p>\n<p>Las mujeres que participen deber\u00e1n manifestar su conformidad con las bases de la convocatoria y autorizan a la dependencia organizadora el uso de sus im\u00e1genes para campa\u00f1as institucionales de prevenci\u00f3n, as\u00ed como para la exposici\u00f3n de las mismas sin fines lucrativos.<\/p>\n<p>El proceso de selecci\u00f3n estar\u00e1 a cargo de profesionales de la fotograf\u00eda y de especialistas en g\u00e9nero y derechos humanos, quienes calificar\u00e1n la calidad conceptual y t\u00e9cnica de las im\u00e1genes, su decisi\u00f3n ser\u00e1 inapelable.<\/p>\n<p>Los resultados se dar\u00e1n a conocer el 20 de marzo de 2020 en la p\u00e1gina de la SMO\u00a0<a href=\"https:\/\/www.oaxaca.gob.mx\/smo\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es-419&amp;q=https:\/\/www.oaxaca.gob.mx\/smo&amp;source=gmail&amp;ust=1584205737906000&amp;usg=AFQjCNHDllbN09Yxw5Sxjx1m7l4GaZ72YA\">https:\/\/www.oaxaca.gob.mx\/smo<\/a>\u00a0. Las fotograf\u00edas finalistas se publicar\u00e1n en las plataformas digitales de la dependencia.<\/p>\n<p>Se premiar\u00e1 al primer lugar con 10 mil pesos, al segundo con 8 mil pesos y al tercer lugar con 5 mil pesos, adem\u00e1s habr\u00e1 tres menciones honorificas de dos mil pesos cada una. Mayores informes en los tel\u00e9fonos 95 110 3458 y 951 321 0759 y en esta liga:\u00a0<a href=\"https:\/\/www.oaxaca.gob.mx\/smo\/concurso-estatal-de-fotografia-resiliencia-y-autonomista-la-libertad-de-las-mujeres\/\" target=\"_blank\" rel=\"noopener noreferrer\" data-saferedirecturl=\"https:\/\/www.google.com\/url?hl=es-419&amp;q=https:\/\/www.oaxaca.gob.mx\/smo\/concurso-estatal-de-fotografia-resiliencia-y-autonomista-la-libertad-de-las-mujeres\/&amp;source=gmail&amp;ust=1584205737906000&amp;usg=AFQjCNHmVGektloqCiBaYNSB9MI6B8uFlw\">https:\/\/www.oaxaca.gob.mx\/smo\/concurso-estatal-de-fotografia-resiliencia-y-autonomista-la-libertad-de-las-mujeres\/<\/a><\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-5154\" src=\"https:\/\/www.oaxaca.gob.mx\/smo\/wp-content\/uploads\/sites\/72\/2020\/03\/ConcursoFotgraf\u00edaSMO.jpg\" alt=\"\" width=\"100%\" srcset=\"https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2020\/03\/ConcursoFotgraf\u00edaSMO.jpg 1280w, https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2020\/03\/ConcursoFotgraf\u00edaSMO-300x274.jpg 300w, https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2020\/03\/ConcursoFotgraf\u00edaSMO-1024x934.jpg 1024w, https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2020\/03\/ConcursoFotgraf\u00edaSMO-768x701.jpg 768w\" sizes=\"(max-width: 1280px) 100vw, 1280px\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ser\u00e1n premiadas tres ganadoras con 10 mil, 8 mil y 5 mil pesos adem\u00e1s de menciones honor\u00edficas con 2 mil pesos Oaxaca de Ju\u00e1rez, Oax. 12 de marzo de 2020. La Secretar\u00eda de las Mujeres de Oaxaca (SMO) invita a fot\u00f3grafas a la 1\u00aa Edici\u00f3n del Concurso de Fotograf\u00eda \u201cResiliencia y autonom\u00eda: la libertad de [&hellip;]<\/p>\n","protected":false},"author":78,"featured_media":5153,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7,8],"tags":[],"class_list":["post-5151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mostrar-en-la-galeria-principal","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 18:40:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/5151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/users\/78"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/comments?post=5151"}],"version-history":[{"count":2,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/5151\/revisions"}],"predecessor-version":[{"id":5156,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/5151\/revisions\/5156"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media\/5153"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media?parent=5151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/categories?post=5151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/tags?post=5151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}