{"id":4858,"date":"2020-01-21T16:24:55","date_gmt":"2020-01-21T22:24:55","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/smo\/?p=4858"},"modified":"2020-01-23T16:35:32","modified_gmt":"2020-01-23T22:35:32","slug":"colaboran-smo-e-immo-en-acciones-que-salvan-vidas","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sm\/colaboran-smo-e-immo-en-acciones-que-salvan-vidas\/","title":{"rendered":"Colaboran SMO e IMMO en acciones que salvan vidas"},"content":{"rendered":"<ul>\n<li>La Casa de Medio Camino, que pone a salvo a mujeres violentadas, recibi\u00f3 mobiliario, material did\u00e1ctico y un veh\u00edculo<\/li>\n<\/ul>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax. 21 de enero de 2020.<\/strong>\u00a0Con el objetivo de fortalecer la atenci\u00f3n especializada a mujeres, en su caso hijas e hijos, v\u00edctimas de violencia de g\u00e9nero, la Secretar\u00eda de las Mujeres de Oaxaca (SMO) entreg\u00f3 a directivas de la Casa de Medio Camino (Camec) mobiliario, material did\u00e1ctico y un veh\u00edculo para transportar a mujeres v\u00edctimas de violencia.<\/p>\n<p>La entrega tambi\u00e9n incluy\u00f3 nueve escritorios, mesa y sillas ejecutivas, dos lavadoras autom\u00e1ticas, estufa, licuadora, extractor, cafetera, seis literas, sala, cambiador de pa\u00f1ales, dos computadoras port\u00e1tiles, dos impresoras, dos pantallas led de 49\u201d, dos b\u00e1sculas pedi\u00e1trica y cl\u00ednica, nebulizador, gluc\u00f3metro y esterilizador, entre otros.<\/p>\n<p>En el marco de la firma de un convenio de colaboraci\u00f3n entre la SMO y el Instituto Municipal de las Mujeres (IMMO), ambas instituciones se comprometieron a promover e impulsar programas, acciones y estrategias para prevenir y atender la violencia de g\u00e9nero y fomentar una cultura de respeto de los derechos humanos de las mujeres.<\/p>\n<p>Al respecto, la titular de la SMO Ana V\u00e1squez Colmenares Guzm\u00e1n, reconoci\u00f3 el trabajo del personal y directiva del IMMO, el cual implica un gran compromiso. \u201cAqu\u00ed no hay horarios ni descanso para salvar vidas y construir nuevos caminos para seguir adelante\u201d, se\u00f1al\u00f3 la funcionaria.<\/p>\n<p>Tambi\u00e9n se comprometi\u00f3 a continuar apoyando en la gesti\u00f3n de m\u00e1s recursos, con cabildeo institucional y como en otros sectores, a fin de reforzar las acciones para cumplir con los resolutivos de la Alerta de G\u00e9nero.<\/p>\n<p>Asimismo, la directora del Instituto Municipal de las Mujeres (IMMO), Jaquelina Escamilla Villanueva agradeci\u00f3 el apoyo de la SMO, por el compromiso asumido por el gobernador Alejandro Murat Hinojosa, en el marco del Sistema Estatal para la Prevenci\u00f3n, Atenci\u00f3n, Sanci\u00f3n y Erradicaci\u00f3n de la Violencia contra las Mujeres (PASEVM).<\/p>\n<p>La consejera ciudadana del IMMO, Vilma\u00a0<em>Katt<\/em>\u00a0Ulloa reconoci\u00f3 que la Camec, a pesar de sus limitaciones y circunstancias ha fungido como un refugio, como resultado del trabajo entre la SMO y el IMMO, para que mujeres violentadas tengan una calidad de vida justa, digna y con acceso a la justicia.<\/p>\n<p>La activista se pronunci\u00f3 por afianzar las redes feministas para trabajar con dependencias de todos los niveles, con la experiencia y acompa\u00f1amiento feminista, porque esas redes mantienen a muchas mujeres con vida, dijo.<\/p>\n<p>En tanto, el Centro PAIMEF de la SMO, brinda atenci\u00f3n especializada a mujeres en situaci\u00f3n de violencia, a sus hijas e hijos y de ser necesario les canaliza a la Camec. Mayor informaci\u00f3n en los siguientes n\u00fameros telef\u00f3nicos: 207 28 36 y 207 26 66.<\/p>\n<p>Se invita a la poblaci\u00f3n que guste aportar alg\u00fan material o producto para la Camec, acudir a las instalaciones del IMMO en Boulevard Manuel Ruiz No. 111, colonia Reforma, tel\u00e9fono 51 4 23 65,\u00a0<a href=\"mailto:contacto@immujeroaxaca.com\" target=\"_blank\" rel=\"noopener noreferrer\">contacto@immujeroaxaca.com<\/a><\/p>\n[custom_gallery source=\u00bbmedia: 4859,4860,4861,4862,4863,4864&#8243; link=\u00bblightbox\u00bb width=\u00bb350&#8243; height=\u00bb220&#8243; title=\u00bbnever\u00bb]\n","protected":false},"excerpt":{"rendered":"<p>La Casa de Medio Camino, que pone a salvo a mujeres violentadas, recibi\u00f3 mobiliario, material did\u00e1ctico y un veh\u00edculo Oaxaca de Ju\u00e1rez, Oax. 21 de enero de 2020.\u00a0Con el objetivo de fortalecer la atenci\u00f3n especializada a mujeres, en su caso hijas e hijos, v\u00edctimas de violencia de g\u00e9nero, la Secretar\u00eda de las Mujeres de Oaxaca [&hellip;]<\/p>\n","protected":false},"author":78,"featured_media":4865,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7,8],"tags":[],"class_list":["post-4858","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mostrar-en-la-galeria-principal","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 18:41:16","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/4858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/users\/78"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/comments?post=4858"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/4858\/revisions"}],"predecessor-version":[{"id":4867,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/4858\/revisions\/4867"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media\/4865"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media?parent=4858"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/categories?post=4858"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/tags?post=4858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}