{"id":4811,"date":"2020-01-13T14:06:56","date_gmt":"2020-01-13T20:06:56","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/smo\/?p=4811"},"modified":"2020-01-14T14:09:14","modified_gmt":"2020-01-14T20:09:14","slug":"difunde-smo-segunda-etapa-de-campana-para-prevenir-la-violencia","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sm\/difunde-smo-segunda-etapa-de-campana-para-prevenir-la-violencia\/","title":{"rendered":"Difunde SMO segunda etapa de campa\u00f1a para prevenir la violencia"},"content":{"rendered":"<p><strong>Difunde SMO segunda etapa de campa\u00f1a para prevenir la violencia<\/strong><\/p>\n<ul>\n<li>\u201cLa violencia contra las mujeres te afecta #AT\u00edTambi\u00e9n\u201c, busca desnaturalizar la tolerancia social ante actos y conductas violentas contra las mujeres<\/li>\n<\/ul>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax. 13 de enero de 2020.<\/strong>\u00a0La Secretar\u00eda de las Mujeres de Oaxaca (SMO) difunde a trav\u00e9s de sus redes sociales la segunda parte de la campa\u00f1a denominada \u201cLa violencia contra las mujeres te afecta #AT\u00edTambi\u00e9n\u201c, con el objetivo de hacer visibles los \u00e1mbitos y tipos de violencia que muchas veces la sociedad considera normales, sin percatarse que les afecta a todas y todos.<\/p>\n<p>Por su parte, la titular de la SMO, Ana V\u00e1squez Colmenares Guzm\u00e1n advierte que como sociedad debemos desnaturalizar la violencia en sus distintas manifestaciones a trav\u00e9s de un cambio cultural, el cual inicia con la toma de conciencia acerca de la permisividad, de la tolerancia y hasta de la indiferencia social.<\/p>\n<p>\u201cCuando reconocemos las conductas, las palabras, las costumbres que vulneran el derecho de las mujeres a vivir sin violencia; estamos en condiciones de emprender cambios primero personales y despu\u00e9s en colectivo, encaminados a construir relaciones personales sanas\u201d, se\u00f1al\u00f3 la funcionaria estatal.<\/p>\n<p>Por ello, con esta campa\u00f1a la SMO busca cambiar la percepci\u00f3n sobre los actos que restringen los derechos de las mujeres y ni\u00f1as, al presentar escenas cotidianas donde la violencia existe y ha sido naturalizada por los roles de g\u00e9nero, por algunas costumbres.<\/p>\n<p>En el material destacan frases como \u201cSi te amenaza con correrte de casa, es violencia; Que controle tu dinero, es violencia; Humillarte en p\u00fablico o en privado, es violencia; Si te obliga a vestir de cierta forma, es violencia\u201d. Asimismo, ofrece una alternativa de apoyo institucional e invita a marcar el 911 o acude al Centro PAIMEF-SMO para mujeres en situaci\u00f3n de violencia. Tambi\u00e9n solicit\u00f3 a los medios y personas interesadas ayudar a difundirlos, pues \u201cla violencia contra las mujeres te afecta a ti tambi\u00e9n\u201d.<\/p>\n<p>Finalmente, V\u00e1squez Colmenares invit\u00f3 a acercarse a las instituciones que brindan informaci\u00f3n y apoyo sobre estos temas, como la SMO, el Centro de Reeducaci\u00f3n para Hombres que Ejercen Violencia de la Secretar\u00eda de Seguridad P\u00fablica; el Centro de Justicia para las Mujeres, de la Fiscal\u00eda General del Estado; las Instancias Municipales de las Mujeres, los Centros para el Desarrollo de las Mujeres, en los municipios.<\/p>\n[custom_gallery source=\u00bbmedia: 4814,4815,4816&#8243; link=\u00bblightbox\u00bb width=\u00bb350&#8243; height=\u00bb220&#8243; title=\u00bbnever\u00bb]\n","protected":false},"excerpt":{"rendered":"<p>Difunde SMO segunda etapa de campa\u00f1a para prevenir la violencia \u201cLa violencia contra las mujeres te afecta #AT\u00edTambi\u00e9n\u201c, busca desnaturalizar la tolerancia social ante actos y conductas violentas contra las mujeres Oaxaca de Ju\u00e1rez, Oax. 13 de enero de 2020.\u00a0La Secretar\u00eda de las Mujeres de Oaxaca (SMO) difunde a trav\u00e9s de sus redes sociales la [&hellip;]<\/p>\n","protected":false},"author":78,"featured_media":4812,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7,8],"tags":[],"class_list":["post-4811","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mostrar-en-la-galeria-principal","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 19:52:04","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/4811","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/users\/78"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/comments?post=4811"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/4811\/revisions"}],"predecessor-version":[{"id":4817,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/4811\/revisions\/4817"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media\/4812"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media?parent=4811"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/categories?post=4811"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/tags?post=4811"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}