{"id":4787,"date":"2020-01-02T17:03:27","date_gmt":"2020-01-02T23:03:27","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/smo\/?p=4787"},"modified":"2020-01-02T17:03:27","modified_gmt":"2020-01-02T23:03:27","slug":"la-smo-refrenda-compromiso-para-seguir-construyendo-un-oaxaca-igualitario","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sm\/la-smo-refrenda-compromiso-para-seguir-construyendo-un-oaxaca-igualitario\/","title":{"rendered":"La SMO refrenda compromiso para seguir construyendo un Oaxaca igualitario"},"content":{"rendered":"<ul>\n<li>A trav\u00e9s de procesos formativos y de capacitaci\u00f3n a todos los sectores<\/li>\n<\/ul>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax. 2 de enero de 2020.<\/strong>\u00a0El avance en la construcci\u00f3n de una igualdad sustantiva y sostenible, as\u00ed como la prevenci\u00f3n de la violencia de g\u00e9nero contra mujeres y ni\u00f1as, como parte del ejercicio del eje transversal de gobierno, solo tiene un camino: trabajo conjunto y constante entre sociedad y gobierno.<\/p>\n<p>El llamado es claro. La Secretar\u00eda de las Mujeres de Oaxaca (SMO), reconoce lo que a\u00fan falta por hacer y mantiene la convicci\u00f3n y compromiso de seguir involucrando a todos los sectores en la entidad en este cambio sociocultural durante el 2020, porque prevenir y erradicar las violencias nos corresponde a todas y todos.<\/p>\n<p>La titular de la SMO, Ana V\u00e1squez Colmenares Guzm\u00e1n asegura que en el 2020 seguir\u00e1 aplic\u00e1ndose el programa de capacitaci\u00f3n integral continua, para fortalecer el conocimiento de mujeres de diferentes instituciones y de poblaci\u00f3n abierta, sobre el respeto y ejercicio de los Derechos Humanos.<\/p>\n<p>Al respecto, en 2019, a trav\u00e9s de las redes de Abogadas y Promotoras Interculturales de la SMO lograron impactar a 23 mil 689 personas en todas las regiones, con actividades y talleres en materia de prevenci\u00f3n de la violencia. Haciendo un gran total de 38 mil 79 personas con herramientas cognitivas para construir relaciones libres de violencia.<\/p>\n<p>Se realizaron 196 capacitaciones, beneficiando a 6 mil 886 personas: 4 mil 858 mujeres y 2 mil 028 hombres. Asimismo, la \u201cJornada Integral de capacitaci\u00f3n para el fomento del autocuidado, prevenci\u00f3n y detecci\u00f3n del abuso sexual infantil en el \u00e1mbito familiar en el estado de Oaxaca\u201d incluy\u00f3 114 presentaciones de teatro gui\u00f1ol.<\/p>\n<p>De igual manera, la funcionaria estatal se\u00f1al\u00f3 que se continuar\u00e1 con las estrategias de concientizaci\u00f3n denominadas \u201cCapacitaci\u00f3n Integral para la Prevenci\u00f3n de la Trata de personas \u201cSi de Trata se Trata\u201d y Prevenci\u00f3n de la Violencia de G\u00e9nero en el Noviazgo \u201cSi Duele no es Amor\u201d, este \u00faltimo dirigido a las y los adolescentes.<\/p>\n<p>Estas acciones informaron sobre los tipos de violencia en dicha etapa, sus consecuencias, c\u00f3mo prevenirlo y a qu\u00e9 instancias pueden acudir a solicitar apoyo. Se atendi\u00f3 a 2 mil 263 j\u00f3venes, 276 directivos, docentes, administrativos, madres y padres de familia<\/p>\n<p>Tambi\u00e9n, con 800 Interacciones did\u00e1cticas a trav\u00e9s de 52 capacitaciones dirigidas a estudiantes de nivel medio superior; 15 capacitaciones y 12 instituciones, se logr\u00f3 una atenci\u00f3n a 4 mil 689 j\u00f3venes, 276 directivos, docentes, administrativos, as\u00ed como madres y padres de familia.<\/p>\n<p>No obstante, en la SMO sabemos que es indispensable continuar con la toma de conciencia de toda la sociedad, advirti\u00f3 V\u00e1squez Colmenares, sobre la importancia de cambiar la forma de relacionarse entre mujeres y hombres, con respeto a las diferencias y reconocimiento a la igualdad de derechos, para seguir avanzando como estado.<\/p>\n[custom_gallery source=\u00bbmedia: 4791,4792,4793&#8243; link=\u00bblightbox\u00bb width=\u00bb350&#8243; height=\u00bb220&#8243; title=\u00bbnever\u00bb]\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de procesos formativos y de capacitaci\u00f3n a todos los sectores Oaxaca de Ju\u00e1rez, Oax. 2 de enero de 2020.\u00a0El avance en la construcci\u00f3n de una igualdad sustantiva y sostenible, as\u00ed como la prevenci\u00f3n de la violencia de g\u00e9nero contra mujeres y ni\u00f1as, como parte del ejercicio del eje transversal de gobierno, solo tiene [&hellip;]<\/p>\n","protected":false},"author":78,"featured_media":4790,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7,8],"tags":[],"class_list":["post-4787","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mostrar-en-la-galeria-principal","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 19:51:59","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/4787","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/users\/78"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/comments?post=4787"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/4787\/revisions"}],"predecessor-version":[{"id":4794,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/4787\/revisions\/4794"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media\/4790"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media?parent=4787"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/categories?post=4787"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/tags?post=4787"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}