{"id":2936,"date":"2019-03-04T15:39:57","date_gmt":"2019-03-04T21:39:57","guid":{"rendered":"http:\/\/www.smo.oaxaca.gob.mx\/?p=2936"},"modified":"2019-03-04T15:39:57","modified_gmt":"2019-03-04T21:39:57","slug":"anuncia-amh-acciones-de-atencion-y-prevencion-contra-la-violencia-hacia-las-mujeres","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sm\/anuncia-amh-acciones-de-atencion-y-prevencion-contra-la-violencia-hacia-las-mujeres\/","title":{"rendered":"Anuncia AMH acciones de atenci\u00f3n y prevenci\u00f3n contra la violencia hacia las mujeres"},"content":{"rendered":"<p>En conferencia de medios, el Mandatario Estatal se\u00f1al\u00f3 que el Gobierno del Estado implementa estrategias a favor de este sector, en el marco del D\u00eda Internacional de la Mujer -8 de marzo-<\/p>\n<p>Al abordar diversos temas, tambi\u00e9n exhort\u00f3 a la poblaci\u00f3n a evitar riesgos por tomas clandestinas de energ\u00eda el\u00e9ctrica<\/p>\n<p>Oaxaca de Ju\u00e1rez, Oax. 4 de marzo de 2019. Como parte de la pol\u00edtica de igualdad que impulsa el Gobierno del Estado y en el marco del D\u00eda Internacional de la Mujer -8 de marzo-, el gobernador Alejandro Murat Hinojosa anunci\u00f3, durante la conferencia de prensa de este lunes, diversas actividades que permitir\u00e1n una transversalidad para la prevenci\u00f3n, atenci\u00f3n y erradicaci\u00f3n de la violencia de g\u00e9nero contra este sector de la poblaci\u00f3n oaxaque\u00f1a.<\/p>\n<p>En este sentido, expuso que en el marco de esta fecha, donde las personas, organizaciones de la sociedad civil y gobiernos se unen para fortalecer los compromisos en alcanzar la igualdad sustantiva entre mujeres y hombres en el mundo, presidir\u00e1 los Sistemas Estatales de Igualdad entre Mujeres y Hombres, y el de Prevenci\u00f3n, Atenci\u00f3n, Sanci\u00f3n y Erradicaci\u00f3n de Violencia de G\u00e9nero contra las Mujeres, los cuales que rigen la pol\u00edtica de igualdad en el estado a fin de establecer estrategias para la prevenci\u00f3n y atenci\u00f3n de la violencia en todas sus formas, particularmente contra las mujeres.<\/p>\n<p>En tanto, la titular de la Secretar\u00eda de las Mujeres de Oaxaca (SMO) Ana V\u00e1squez Colmenares, anunci\u00f3 que por primera vez este organismo ejercer\u00e1 recursos para proyectos de inversi\u00f3n para la prevenci\u00f3n y atenci\u00f3n en contra de la violencia de g\u00e9nero; se contar\u00e1 con una Casa de Medio Camino para Mujeres en situaci\u00f3n de violencia, se brindar\u00e1n micro cr\u00e9ditos a la Palabra de la Mujer y se impulsar\u00e1 el Programa \u201cMujeres que nos inspiran\u201d para apoyar a oaxaque\u00f1as talentosas y emprendedoras de distintas regiones de la entidad.<\/p>\n<p>Durante este mes -dijo-, se presentar\u00e1 el Atlas de G\u00e9nero Oaxaca, el lanzamiento del proyecto: Puedes ser lo que Sue\u00f1es, estrategia de promoci\u00f3n de derechos con el IEEPO y la Instalaci\u00f3n de Consejos Municipales para la Prevenci\u00f3n, Atenci\u00f3n, Sanci\u00f3n y Erradicaci\u00f3n de Violencia de G\u00e9nero contra las Mujeres en Villa Tututepec, Santo Domingo de Morelos, Santa Mar\u00eda Tonameca, Santa Mar\u00eda Huatulco y Valle Nacional.<\/p>\n<p>Se exhorta a la poblaci\u00f3n a evitar tomas clandestinas de energ\u00eda el\u00e9ctrica: AMH<\/p>\n<p>Durante este encuentro con representantes de los medios de comunicaci\u00f3n, el gobernador Alejandro Murat Hinojosa destac\u00f3 que para salvaguardar la integridad de la poblaci\u00f3n oaxaque\u00f1a instruy\u00f3 a la Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil de Oaxaca (CEPCO) coadyuve para evitar las tomas clandestinas de energ\u00eda el\u00e9ctrica que se derivan de instalaciones el\u00e9ctricas improvisadas o ilegales y que pueden causar graves accidentes.<\/p>\n<p>Al respecto el titular de CEPCO, Heliodoro D\u00edaz Esc\u00e1rraga, explic\u00f3 que en coordinaci\u00f3n con personal de la Comisi\u00f3n Federal de Electricidad (CFE) y el municipio de Oaxaca de Ju\u00e1rez, se realiz\u00f3 al corte de energ\u00eda a 19 puntos efectivos y estrat\u00e9gicos del Centro Hist\u00f3rico de la capital oaxaque\u00f1a, para evitar 200 conexiones irregulares.<\/p>\n<p>Dijo que se tiene el reporte de p\u00e9rdidas por m\u00e1s de 1.55 millones de pesos durante el mes de febrero por estas pr\u00e1cticas irregulares que se realizan principalmente en puestos ambulantes, comercios establecidos y poblaci\u00f3n en general. Este organismo exhort\u00f3 a la poblaci\u00f3n se abstenga de realizar estas acciones por el riesgo que representan. Se\u00f1al\u00f3 que se impulsar\u00e1n un plan estrat\u00e9gico para atender esta situaci\u00f3n en la Central de Abasto de la capital oaxaque\u00f1a.<\/p>\n<p>Apoyo a Educaci\u00f3n Media y Superior de Oaxaca<\/p>\n<p>En su oportunidad el coordinador general de Educaci\u00f3n Media Superior y Superior, Ciencia y Tecnolog\u00eda (CGEMSySCyT) Francisco M\u00e1rquez M\u00e9ndez se\u00f1al\u00f3 que el Gobernador realiza gestiones ante la Federaci\u00f3n para contar con mayores recursos a favor de las y los j\u00f3venes oaxaque\u00f1os. Expuso que en educaci\u00f3n media superior se ha invertido 44 millones de pesos para los planteles de bachillerato y con ello disminuir los \u00edndices de deserci\u00f3n; para educaci\u00f3n superior se han canalizado 625 millones de pesos, lo que permita contar una mayor infraestructura educativa y brindar una oferta de 500 carreras profesionales.<\/p>\n<p>Destac\u00f3 que el Gobierno del Estado canaliz\u00f3 recursos por m\u00e1s de 26 millones 400 mil pesos del Programa Estatal de Becas de Educaci\u00f3n Superior de Oaxaca (PEBESO) para atender a las y los becarios que se les suspendi\u00f3 el apoyo durante el periodo septiembre a diciembre de 2018 por el cambio de operatividad del programa federal.<\/p>\n<p>A la conferencia de medios tambi\u00e9n asistieron la directora del Consejo Estatal para la Prevenci\u00f3n y Control del Sida (Coesida), Gabriela Vel\u00e1squez Rosas, quien expuso los logros y acciones que ha realizado este organismo. Tambi\u00e9n particip\u00f3 la titular de la Comisi\u00f3n Estatal de Cultura F\u00edsica y Deporte (Cecude) Montserrat Arag\u00f3n Heinze, quien inform\u00f3 que se contin\u00faan con los preparativos del Medio Marat\u00f3n Rock and Roll 2019 a realizarse el pr\u00f3ximo 17 de marzo, en la ciudad de Oaxaca.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>En conferencia de medios, el Mandatario Estatal se\u00f1al\u00f3 que el Gobierno del Estado implementa estrategias a favor de este sector, en el marco del D\u00eda Internacional de la Mujer -8 de marzo- Al abordar diversos temas, tambi\u00e9n exhort\u00f3 a la poblaci\u00f3n a evitar riesgos por tomas clandestinas de energ\u00eda el\u00e9ctrica Oaxaca de Ju\u00e1rez, Oax. 4 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2938,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7,8],"tags":[],"class_list":["post-2936","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mostrar-en-la-galeria-principal","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 03:07:45","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/2936","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/comments?post=2936"}],"version-history":[{"count":0,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/2936\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media\/2938"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media?parent=2936"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/categories?post=2936"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/tags?post=2936"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}