{"id":2399,"date":"2018-11-22T09:37:01","date_gmt":"2018-11-22T15:37:01","guid":{"rendered":"http:\/\/www.smo.oaxaca.gob.mx\/?p=2399"},"modified":"2018-11-22T09:37:01","modified_gmt":"2018-11-22T15:37:01","slug":"smo-realiza-el-foro-agenda-legislativa-para-erradicar-la-violencia-de-genero","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sm\/smo-realiza-el-foro-agenda-legislativa-para-erradicar-la-violencia-de-genero\/","title":{"rendered":"SMO realiza el Foro Agenda Legislativa para Erradicar la Violencia de G\u00e9nero"},"content":{"rendered":"<ul>\n<li>Las propuestas ser\u00e1n entregadas a la LXIV Legislatura Local<\/li>\n<\/ul>\n<p>Oaxaca de Ju\u00e1rez, Oax., 22 de noviembre de 2018.- La titular de la Secretar\u00eda de la Mujer Oaxaque\u00f1a (SMO), Ana V\u00e1squez Colmenares Guzm\u00e1n inaugur\u00f3 el Foro \u201cAgenda Legislativa para Erradicar la Discriminaci\u00f3n y Violencia contra las Mujeres en Oaxaca\u201d, del cual emanaron sugerencias, recomendaciones y propuestas de armonizaci\u00f3n legislativa que ser\u00e1n entregadas a las y los integrantes de la LXIV Legislatura Local.<\/p>\n<p>Tras se\u00f1alar cifras sobre este fen\u00f3meno de violencia de g\u00e9nero con dimensi\u00f3n de emergencia social, el Coordinador Jur\u00eddico del Instituto Nacional de las Mujeres (Inmujeres), Pablo Navarrete Guti\u00e9rrez, argument\u00f3 que se necesita fortalecer institucionalmente los mecanismos para el fortalecimiento y presencia de las mujeres en toda la administraci\u00f3n p\u00fablica de todos los niveles.<\/p>\n<p>Esto dijo, a trav\u00e9s de reformas a la Ley Org\u00e1nica Municipal, para que las Instancias Municipales de las Mujeres (IMM)\u00a0 y las Unidades de G\u00e9nero permanezcan aunque cambien los gobiernos.<\/p>\n<p>Por su parte, V\u00e1squez Colmenares afirm\u00f3 que mientras los estereotipos y cualquier tipo de discriminaci\u00f3n de g\u00e9nero persistan en nuestra cotidianidad, la violencia de g\u00e9nero seguir\u00e1.<\/p>\n<p>Asimismo, inform\u00f3 que a la fecha 25 de los 40 municipios declarados con Alerta de G\u00e9nero han instalado sus respectivos Consejos Municipales para la Prevenci\u00f3n, Atenci\u00f3n, Sanci\u00f3n y Erradicaci\u00f3n de la Violencia de G\u00e9nero.<\/p>\n<p>En tanto, quienes formaron parte del panel como la investigadora y funcionaria del Consejo Nacional para Prevenir la Discriminaci\u00f3n (Conapred), Martha Ferreyra Beltr\u00e1n,\u00a0 as\u00ed como la investigadora de la Universidad Aut\u00f3noma Benito Ju\u00e1rez de Oaxaca (UABJO), Leticia Brise\u00f1o Mass,\u00a0 coincidieron en que es fundamental tener presupuestos etiquetados transversales para mujeres, con indicadores de cumplimiento; adem\u00e1s de revisar el marco normativo civil y penal para eliminar la disparidad del tipo penal del feminicidio y de las penas.<\/p>\n<p>Es necesario tambi\u00e9n, dijeron, tener un r\u00e9gimen de responsabilidades jur\u00eddicas para las autoridades omisas y no olvidar que combatir la violencia es una responsabilidad compartida, por lo que el urgente y profundo cambio social y cultural requiere la participaci\u00f3n de todas y todos.<\/p>\n<p>Ante titulares de los IMM, de las Unidades de G\u00e9nero e integrantes de organizaciones de la sociedad civil,\u00a0 se enfatiz\u00f3 que la sociedad mexicana es machista y mis\u00f3gina, pues de acuerdo al informe presentado por la Comisi\u00f3n Econ\u00f3mica para Am\u00e9rica Latina y el Caribe (CEPAL), sobre muertes violentas en esta regi\u00f3n, M\u00e9xico ocupa el primer lugar en el continente como el pa\u00eds m\u00e1s violento contra las mujeres, por lo que el llamado a la condena social de la violencia contra las mujeres debe ser compartido.<\/p>\n<p>En las tres mesas de trabajo de dicho foro se abordaron temas como \u201cViolencia feminicida. Retos para combatirla\u201d, \u201cRetos para la transversalizaci\u00f3n de pol\u00edticas p\u00fablicas de igualdad entre mujeres y hombres\u201d y \u201cAlerta de Violencia de G\u00e9nero contra las Mujeres, caso Oaxaca\u201d, de las cuales\u00a0 surgieron propuestas concretas como impulsar la investigaci\u00f3n acad\u00e9mica en g\u00e9nero con un enfoque de interculturalidad.<\/p>\n<p>Asimismo se pronunciaron por impulsar la capacitaci\u00f3n del funcionariado p\u00fablico en materia de derechos humanos e involucrar al personal docente en la desnaturalizaci\u00f3n de la violencia contra las mujeres desde la escuela e incluir en los programas educativos la asignatura de g\u00e9nero.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las propuestas ser\u00e1n entregadas a la LXIV Legislatura Local Oaxaca de Ju\u00e1rez, Oax., 22 de noviembre de 2018.- La titular de la Secretar\u00eda de la Mujer Oaxaque\u00f1a (SMO), Ana V\u00e1squez Colmenares Guzm\u00e1n inaugur\u00f3 el Foro \u201cAgenda Legislativa para Erradicar la Discriminaci\u00f3n y Violencia contra las Mujeres en Oaxaca\u201d, del cual emanaron sugerencias, recomendaciones y propuestas [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2400,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7,8],"tags":[],"class_list":["post-2399","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mostrar-en-la-galeria-principal","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 04:21:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/2399","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/comments?post=2399"}],"version-history":[{"count":0,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/2399\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media\/2400"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media?parent=2399"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/categories?post=2399"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/tags?post=2399"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}