{"id":2229,"date":"2018-09-28T09:05:20","date_gmt":"2018-09-28T15:05:20","guid":{"rendered":"http:\/\/www.smo.oaxaca.gob.mx\/?p=2229"},"modified":"2018-09-28T09:05:20","modified_gmt":"2018-09-28T15:05:20","slug":"smo-invita-a-los-hombres-a-descubrir-nuevas-masculinidades","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sm\/smo-invita-a-los-hombres-a-descubrir-nuevas-masculinidades\/","title":{"rendered":"SMO invita a los hombres a descubrir nuevas masculinidades"},"content":{"rendered":"<ul>\n<li>Los roles de g\u00e9nero impuestos limitan la forma de relacionarse y resolver conflictos de los hombres.<\/li>\n<\/ul>\n<p>Oaxaca de Ju\u00e1rez, Oax. a 28 de septiembre de 2018.- La Secretar\u00eda de la Mujer Oaxaque\u00f1a (SMO) realiz\u00f3 los Talleres de Nuevas Masculinidades, a cargo de la investigadora en temas de g\u00e9nero, Guadalupe Peralta, impartido a titulares de Centros para el Desarrollo de las Mujeres de las Instancias Municipales de la Mujer y representantes de dependencias del gobierno estatal, quienes coincidieron en reconocer que existe una presi\u00f3n cultural e institucional hacia los hombres que los enmarca en un modelo estereotipado, caracterizado por la violencia, dominaci\u00f3n, control, detentaci\u00f3n de poder econ\u00f3mico, rechazo a lo femenino y la heterosexualidad obligatoria.<\/p>\n<p>Los hombres pueden ser m\u00e1s felices, mejorar sus habilidades de comunicaci\u00f3n y de empat\u00eda, sentirse m\u00e1s libres, evitar tragedias como homicidios, perder el miedo e incluso superar prejuicios, en la medida que deconstruyan sus masculinidades y se permitan reaprender a c\u00f3mo ser hombre partiendo de la igualdad de g\u00e9nero que implica beneficios a las familias, las comunidades y a todo el pa\u00eds.<\/p>\n<p>El sexismo impide el desarrollo del ser humano, se\u00f1al\u00f3 la capacitadora, pues discrimina y oprime a las mujeres, pero tambi\u00e9n limita a los hombres, por ello es preciso un cambio profundo, institucional y cultural. Esto mediante una participaci\u00f3n m\u00e1s activa y profunda de los hombres en los esfuerzos por la equidad de g\u00e9nero, sin un enfoque jer\u00e1rquico, pues normalmente se concibe a la masculinidad como una\u00a0serie de valores, actitudes y mitos y que no necesariamente todos los hombres se sienten c\u00f3modos tratando de cumplir estas expectativas.<\/p>\n<p>Las nuevas masculinidades implican aceptar una corresponsabilidad real en la reproducci\u00f3n, el cuidado de hijas e\u00a0hijos y personas de la tercera edad, as\u00ed como de las tareas dom\u00e9sticas y otras actividades asignadas a las mujeres. El g\u00e9nero no tiene que decir c\u00f3mo alcanzar la felicidad o la realizaci\u00f3n personal.<\/p>\n<p>Los asistentes provenientes de municipios como San Marcial Ozolotepec, Santiago Juxtlahuaca, Santa Cruz Zenzontepec, Tamazulapam del Esp\u00edritu Santo, Santiago Textitl\u00e1n, Santiago Tlazoyaltepec, San Pedro Amuzgos, San Pablo Ayutla, San Juan Bautista Cuicatl\u00e1n, Santa Mar\u00eda Teopoxco, Santa In\u00e9s Yatzeche, Zimatl\u00e1n de \u00c1lvarez, San Bartolom\u00e9 Quialana, San Pedro Huixtepec, Tlacolula de Matamoros, Oaxaca de Ju\u00e1rez, San Antonino el Alto y Villa de Zaachila, conocieron temas sobre masculinidades, machismo, feminidades, estereotipos, entre otros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los roles de g\u00e9nero impuestos limitan la forma de relacionarse y resolver conflictos de los hombres. Oaxaca de Ju\u00e1rez, Oax. a 28 de septiembre de 2018.- La Secretar\u00eda de la Mujer Oaxaque\u00f1a (SMO) realiz\u00f3 los Talleres de Nuevas Masculinidades, a cargo de la investigadora en temas de g\u00e9nero, Guadalupe Peralta, impartido a titulares de Centros [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2231,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7,8],"tags":[],"class_list":["post-2229","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mostrar-en-la-galeria-principal","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 05:30:32","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/2229","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/comments?post=2229"}],"version-history":[{"count":0,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/2229\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media\/2231"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media?parent=2229"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/categories?post=2229"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/tags?post=2229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}