{"id":2208,"date":"2018-09-19T14:04:28","date_gmt":"2018-09-19T20:04:28","guid":{"rendered":"http:\/\/www.smo.oaxaca.gob.mx\/?p=2208"},"modified":"2018-09-19T14:04:28","modified_gmt":"2018-09-19T20:04:28","slug":"atestigua-smo-lanzamiento-de-la-plataforma-nacional-mexico-rumbo-a-la-igualdad","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sm\/atestigua-smo-lanzamiento-de-la-plataforma-nacional-mexico-rumbo-a-la-igualdad\/","title":{"rendered":"Atestigua SMO lanzamiento de la plataforma nacional \u00abM\u00e9xico Rumbo a la Igualdad\u00bb"},"content":{"rendered":"<ul>\n<li>A trav\u00e9s de esta herramienta, se medir\u00e1n los progresos en igualdad de g\u00e9nero, de las 32 entidades federativas del pa\u00eds, incluyendo Oaxaca.<\/li>\n<\/ul>\n<p>Ciudad de M\u00e9xico. 18 de septiembre de 2018. Con la representaci\u00f3n del Gobernador Alejandro Murat Hinojosa ante la Conferencia Nacional de Gobernadores (Conago), la titular de la Secretar\u00eda de la Mujer Oaxaque\u00f1a (SMO), Ana V\u00e1squez Colmenares atestigu\u00f3 el lanzamiento de la plataforma \u201cM\u00e9xico Rumbo a la Igualdad\u201d, que impulsa el Instituto Nacional de las Mujeres (Inmujeres).<\/p>\n<p>A trav\u00e9s de esta herramienta, la cual medir\u00e1 los progresos en igualdad de g\u00e9nero, se permitir\u00e1 a las 32 entidades federativas del pa\u00eds &#8211; incluyendo Oaxaca-, conocer los avances y \u00e1reas de oportunidad de los marcos normativos, instrumentos de pol\u00edticas p\u00fablicas, presupuestos y de rendici\u00f3n de cuentas en materia de transversalizaci\u00f3n con enfoque de g\u00e9nero.<\/p>\n<p>Durante el encuentro, convocado por la Conago y el Inmujeres se instal\u00f3 la Comisi\u00f3n de Vinculaci\u00f3n con las Entidades Federativas del Sistema Nacional para la Igualdad entre Mujeres y Hombres, la cual permitir\u00e1 armonizar las pol\u00edticas p\u00fablicas locales con los objetivos de la pol\u00edtica nacional en materia de igualdad, as\u00ed como la normatividad local en la materia, con la federal y a su vez con los instrumentos internacionales correspondientes.<\/p>\n<p>A trav\u00e9s de la plataforma \u201cM\u00e9xico Rumbo a la Igualdad\u201d, los Ejecutivos Estatales y Congresos locales podr\u00e1n compartir buenas pr\u00e1cticas y tomar medidas armonizadas, dado el contenido de la misma, donde es posible encontrar programas para la igualdad, presupuesto y cuenta p\u00fablica (condiciones y asignaciones) y ejercicio del gasto.<\/p>\n<p>As\u00ed como metodolog\u00edas de contenido de las matrices, de An\u00e1lisis de Resultados sobre la informaci\u00f3n que se presenta; periodos de la informaci\u00f3n: hallazgos y resultados de cada entidad federativa organizados en siete matrices que revisan diferentes instrumentos; Glosario normativo, marcos legales nacionales e internacionales para la igualdad entre mujeres y hombres; l\u00edneas de trabajo para cada entidad federativa, entre otros.<\/p>\n<p>La encargada de la pol\u00edtica de igualdad entre mujeres y hombres en la entidad expres\u00f3 que esta herramienta es de f\u00e1cil acceso y manejo, con una actualizaci\u00f3n constante administrada desde el Inmujeres, por lo que invit\u00f3 a conocer la plataforma en la siguiente liga http:\/\/rumboalaigualdad.inmujeres.gob.mx 19o en la p\u00e1gina web de la SMO <a href=\"http:\/\/www.smo.oaxaca.gob.mx\">www.smo.oaxaca.gob.mx<\/a>.<\/p>\n<p>En este encuentro asistieron la Secretaria Ejecutiva del Inmujeres, Marcela Eternod Ar\u00e1mburu, y la representante de ONU Mujeres M\u00e9xico, Bel\u00e9n Sanz Luque, de ONU Mujeres M\u00e9xico quien coincidieron que esta plataforma ser\u00e1 utilizada para incidir en los cambios legislativos y normativos que se requieren para contar con verdaderas pol\u00edticas p\u00fablicas y una gobernanza para la igualdad a favor de las mujeres del pa\u00eds.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s de esta herramienta, se medir\u00e1n los progresos en igualdad de g\u00e9nero, de las 32 entidades federativas del pa\u00eds, incluyendo Oaxaca. Ciudad de M\u00e9xico. 18 de septiembre de 2018. Con la representaci\u00f3n del Gobernador Alejandro Murat Hinojosa ante la Conferencia Nacional de Gobernadores (Conago), la titular de la Secretar\u00eda de la Mujer Oaxaque\u00f1a (SMO), [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2204,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7,8],"tags":[],"class_list":["post-2208","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mostrar-en-la-galeria-principal","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:47:30","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/2208","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/comments?post=2208"}],"version-history":[{"count":0,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/2208\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media\/2204"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media?parent=2208"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/categories?post=2208"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/tags?post=2208"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}