{"id":2194,"date":"2018-09-17T11:51:21","date_gmt":"2018-09-17T17:51:21","guid":{"rendered":"http:\/\/www.smo.oaxaca.gob.mx\/?p=2194"},"modified":"2018-09-17T11:51:21","modified_gmt":"2018-09-17T17:51:21","slug":"laboratorio-de-cohesion-social-ii-y-la-smo-impulsan-derechos-agrarios-de-mujeres","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sm\/laboratorio-de-cohesion-social-ii-y-la-smo-impulsan-derechos-agrarios-de-mujeres\/","title":{"rendered":"Laboratorio de Cohesi\u00f3n Social II y la SMO impulsan derechos agrarios de mujeres"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2198 alignnone\" src=\"\/smo\/wp-content\/uploads\/sites\/72\/2018\/09\/SMO-Encuentro-Mujeres-Agrario-6-1024x576.jpeg\" alt=\"\" width=\"350\" height=\"197\" srcset=\"https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2018\/09\/SMO-Encuentro-Mujeres-Agrario-6-1024x576.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2018\/09\/SMO-Encuentro-Mujeres-Agrario-6-300x169.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2018\/09\/SMO-Encuentro-Mujeres-Agrario-6-768x432.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2018\/09\/SMO-Encuentro-Mujeres-Agrario-6.jpeg 1280w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2197 alignnone\" src=\"\/smo\/wp-content\/uploads\/sites\/72\/2018\/09\/SMO-Encuentro-Mujeres-Agrario-5-1024x576.jpeg\" alt=\"\" width=\"351\" height=\"197\" srcset=\"https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2018\/09\/SMO-Encuentro-Mujeres-Agrario-5-1024x576.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2018\/09\/SMO-Encuentro-Mujeres-Agrario-5-300x169.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2018\/09\/SMO-Encuentro-Mujeres-Agrario-5-768x432.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2018\/09\/SMO-Encuentro-Mujeres-Agrario-5.jpeg 1280w\" sizes=\"auto, (max-width: 351px) 100vw, 351px\" \/><\/p>\n<ul>\n<li>Se llev\u00f3 a cabo el Encuentro de Mujeres en Cargos de Representaci\u00f3n Agraria del Estado Oaxaca.<\/li>\n<\/ul>\n<p>Santa Mar\u00eda del Tule, Oax. 17 de septiembre de 2018. El derecho de las mujeres al uso y usufructo de la tierra es un asunto de justicia social, un piso m\u00ednimo para su autonom\u00eda, as\u00ed lo reconoci\u00f3 la titular de la Secretar\u00eda de la Mujer Oaxaque\u00f1a (SMO), Ana V\u00e1squez Colmenares al inaugurar el Encuentro de Mujeres en Cargos de Representaci\u00f3n Agraria del Estado Oaxaca.<\/p>\n<p>La funcionaria destac\u00f3 que este encuentro es de la mayor relevancia, en un contexto en el que las mujeres rurales representan m\u00e1s de un tercio de la poblaci\u00f3n mundial y el 43% de la mano de obra agr\u00edcola, y sin embargo, se calcula que solo poseen el 1% de la tierra a nivel mundial.<\/p>\n<p>Tambi\u00e9n se refiri\u00f3 que es el resultado de la etapa de cierre del Laboratorio de Cohesi\u00f3n Social II, esfuerzo de cooperaci\u00f3n internacional entre la Uni\u00f3n Europea, la Agencia Mexicana de Cooperaci\u00f3n Internacional para el Desarrollo (AMEXCID) y el Gobierno de Oaxaca, del cual se ha logrado incidir en ejes clave para el desarrollo del estado, como lo es la implementaci\u00f3n de pol\u00edticas p\u00fablicas a favor del adelanto de las mujeres en sus comunidades y la defensa de los derechos humanos como elemento fundamental y de cohesi\u00f3n social.<\/p>\n<p>En Oaxaca, refiri\u00f3 V\u00e1squez Colmenares, de cada 100 personas con derechos agrarios, 28 son mujeres, tambi\u00e9n el 82% del uso del suelo en el estado est\u00e1 catalogado como ejidal y comunal, del cual las mujeres representan tan solo el 4% de las presidencias de Comisariados y Consejos de Vigilancia.<\/p>\n<p>\u201cDe ah\u00ed la importancia de abrir espacios para el intercambio de experiencias de mujeres con representaci\u00f3n agraria, donde juntos podamos comprender las situaciones a las que se enfrentan y generar sinergias que ayuden a disminuir las desigualdades con mayor efectividad\u201d, resalt\u00f3.<\/p>\n<p>Desde la SMO se continuar\u00e1 con las acciones para fortalecer las estrategias de transversalizaci\u00f3n de la pol\u00edtica de g\u00e9nero, propiciando cohesi\u00f3n con la sociedad civil, instituciones Federales como la Procuradur\u00eda Agraria, el Registro Agrario Nacional, la Comisi\u00f3n Nacional Forestal, autoridades municipales y n\u00facleos agrarios, puntualiz\u00f3 V\u00e1squez Colmenares.<\/p>\n<p>A trav\u00e9s del Laboratorio se han llevado a cabo acciones como talleres, asesor\u00edas jur\u00eddicas, asambleas comunitarias, participaci\u00f3n en la creaci\u00f3n de reglamentaciones internas con enfoque de g\u00e9nero. En esta ocasi\u00f3n integrantes del Estatuto Comunal de San Bartolom\u00e9 Quialana compartieron su experiencia de trabajo coordinado a trav\u00e9s de un video; as\u00ed tambi\u00e9n los Comisariados de Bienes Comunales de Santo Domingo Ixcatl\u00e1n y de San Jer\u00f3nimo Tec\u00f3atl expusieron los desaf\u00edos de\u00a0 ejercer cargos de representaci\u00f3n y vigilancia.<\/p>\n<p>En el marco de este encuentro se present\u00f3 la Conferencia Magistral \u00abMujeres con Derechos Agrarios: Formas de Adquisici\u00f3n de Derechos\u00bb a cargo de Alfredo Ram\u00edrez G\u00f3mez, funcionario de la Procuradur\u00eda Agraria.<\/p>\n<p>En tanto, integrantes del Consejo de Vigilancia de San Bartolom\u00e9 Quialana se refirieron a las Normas internas de organizaci\u00f3n, uso, aprovechamiento y conservaci\u00f3n de los recursos naturales, con mirada de g\u00e9nero. Cabe se\u00f1alar que sobre dichos temas se abundaron en tres mesas de trabajo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Se llev\u00f3 a cabo el Encuentro de Mujeres en Cargos de Representaci\u00f3n Agraria del Estado Oaxaca. Santa Mar\u00eda del Tule, Oax. 17 de septiembre de 2018. El derecho de las mujeres al uso y usufructo de la tierra es un asunto de justicia social, un piso m\u00ednimo para su autonom\u00eda, as\u00ed lo reconoci\u00f3 la titular [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2196,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7,8],"tags":[],"class_list":["post-2194","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mostrar-en-la-galeria-principal","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 06:46:53","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/2194","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/comments?post=2194"}],"version-history":[{"count":0,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/2194\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media\/2196"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media?parent=2194"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/categories?post=2194"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/tags?post=2194"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}