{"id":2144,"date":"2018-08-28T08:28:37","date_gmt":"2018-08-28T14:28:37","guid":{"rendered":"http:\/\/www.smo.oaxaca.gob.mx\/?p=2144"},"modified":"2018-08-28T08:28:37","modified_gmt":"2018-08-28T14:28:37","slug":"arranca-segunda-fase-de-rompiendo-estereotipos-mujeres-se-capacitan-como-electricistas","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sm\/arranca-segunda-fase-de-rompiendo-estereotipos-mujeres-se-capacitan-como-electricistas\/","title":{"rendered":"Arranca segunda fase de \u201cRompiendo Estereotipos\u201d, mujeres se capacitan como electricistas"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-2145 alignnone\" src=\"\/smo\/wp-content\/uploads\/sites\/72\/2018\/08\/Arranca-segunda-fase-de-\u201cRompiendo-Estereotipos\u201d-mujeres-se-capacitan-como-electricistas-1-1024x682.jpeg\" alt=\"\" width=\"600\" height=\"399\" srcset=\"https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2018\/08\/Arranca-segunda-fase-de-\u201cRompiendo-Estereotipos\u201d-mujeres-se-capacitan-como-electricistas-1-1024x682.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2018\/08\/Arranca-segunda-fase-de-\u201cRompiendo-Estereotipos\u201d-mujeres-se-capacitan-como-electricistas-1-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2018\/08\/Arranca-segunda-fase-de-\u201cRompiendo-Estereotipos\u201d-mujeres-se-capacitan-como-electricistas-1-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/sm\/wp-content\/uploads\/sites\/72\/2018\/08\/Arranca-segunda-fase-de-\u201cRompiendo-Estereotipos\u201d-mujeres-se-capacitan-como-electricistas-1.jpeg 1280w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/p>\n<ul>\n<li>22 Mujeres que reci\u00e9n culminaron su formaci\u00f3n como plomeras, fortalecen sus conocimientos en otra especialidad.<\/li>\n<\/ul>\n<p>Magdalena Apasco, Etla, Oax. 27 de agosto de 2018.- Inici\u00f3 la segunda fase del proceso de capacitaci\u00f3n hacia el empoderamiento de las mujeres, con el Taller de Electricidad a quienes recientemente egresaron de la formaci\u00f3n como plomeras, como resultado del esfuerzo conjunto entre la Secretar\u00eda de la Mujer Oaxaque\u00f1a (SMO) Secretar\u00eda de Desarrollo Social y Humano (Sedesoh) y el Instituto de Capacitaci\u00f3n y Productividad para el Trabajo (Icapet).<\/p>\n<p>Las instalaciones de la Unidad de Capacitaci\u00f3n n\u00famero 85 del Icapet, ubicado en Magdalena Apasco, Etla, fue el escenario donde entusiastas mujeres convencidas de que \u201cpara seguir aprendiendo m\u00e1s, s\u00f3lo existen las barreras que cada una de nosotras nos pongamos\u201d, se\u00f1al\u00f3 Ram\u00edrez Cruz Cristina, una de las 22 alumnas que incrementar\u00e1n sus posibilidades de auto-emplearse o formar su propia empresa de servicios especializados.<\/p>\n<p>Las futuras electricistas se comprometieron a brindar su mejor esfuerzo y aprovechar cada sesi\u00f3n que les permitir\u00e1 complementar su formaci\u00f3n y ofrecer servicios integrales en cuanto a reparaciones del hogar, trabajos de iluminaci\u00f3n y decoraci\u00f3n en casa habitaci\u00f3n y hasta en industrias, ante la autoridad municipal encabezada por Francisco Ch\u00e1vez Santiago; la titular de Sedesoh, Yolanda Mart\u00ednez L\u00f3pez; la titular de la SMO, Ana V\u00e1squez Colmenares Guzm\u00e1n y el director del Icapet, Francisco \u00c1ngel Maldonado Mart\u00ednez.<\/p>\n<p>Al declarar inaugurado el curso, la Secretaria de Desarrollo Social y Humano, Yolanda Mart\u00ednez L\u00f3pez manifest\u00f3 que la iniciativa \u201cRompiendo Estereotipos\u201d, lograda como Gobierno del Estado en Sinergia con Petr\u00f3leos Mexicanos (Pemex), pretende formar a mujeres en actividades que tradicionalmente eran considerados exclusivamente para hombres.<\/p>\n<p>Durante la ceremonia de inauguraci\u00f3n, la encargada de la pol\u00edtica de igualdad sustantiva en la entidad, Ana V\u00e1squez Colmenares, se pronunci\u00f3 por seguir impulsando, desde el gobierno encabezado por Alejandro Murat Hinojosa, acciones como \u00e9sta que adem\u00e1s de romper estereotipos de g\u00e9nero y vencer resistencias individuales, aportamos a la disminuci\u00f3n de brechas de desigualdad.<\/p>\n<p>Y afirm\u00f3 que durante el actual curso las participantes podr\u00e1n identificar problemas el\u00e9ctricos cotidianos, pues entre los temas a conocer se encuentran: c\u00f3mo reconocer una instalaci\u00f3n el\u00e9ctrica segura, el interruptor diferencial (disyuntor), puesta a tierra, c\u00f3mo detectar un problema el\u00e9ctrico, entre otros.<\/p>\n<p>Por su parte, el director general del Icapet, destac\u00f3 que \u201ccuando una mujer se capacita y realiza una actividad productiva rompe paradigmas y aporta a la vida econ\u00f3mica del estado\u201d.<\/p>\n<p>Cabe hacer menci\u00f3n que el material para el curso con una capacidad hasta para 22 participantes, fue proporcionado por la Sedesoh y otra parte fue donada por la empresa \u201cEl\u00e9ctrica Mexicana\u201d, por lo que agradecieron a la iniciativa privada por la suma de esfuerzos en estas acciones a favor de las mujeres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>22 Mujeres que reci\u00e9n culminaron su formaci\u00f3n como plomeras, fortalecen sus conocimientos en otra especialidad. Magdalena Apasco, Etla, Oax. 27 de agosto de 2018.- Inici\u00f3 la segunda fase del proceso de capacitaci\u00f3n hacia el empoderamiento de las mujeres, con el Taller de Electricidad a quienes recientemente egresaron de la formaci\u00f3n como plomeras, como resultado del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2146,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7,8],"tags":[],"class_list":["post-2144","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mostrar-en-la-galeria-principal","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 08:12:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/2144","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/comments?post=2144"}],"version-history":[{"count":0,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/2144\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media\/2146"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media?parent=2144"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/categories?post=2144"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/tags?post=2144"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}