{"id":1937,"date":"2018-07-10T15:47:10","date_gmt":"2018-07-10T21:47:10","guid":{"rendered":"http:\/\/www.smo.oaxaca.gob.mx\/?p=1937"},"modified":"2018-07-10T15:47:10","modified_gmt":"2018-07-10T21:47:10","slug":"invita-smo-a-la-segunda-feria-de-la-sororidad","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sm\/invita-smo-a-la-segunda-feria-de-la-sororidad\/","title":{"rendered":"Invita SMO a la Segunda Feria de la Sororidad"},"content":{"rendered":"<ul>\n<li>M\u00e1s de 60 artesanas de todas las regiones ofertar\u00e1n sus productos en la Biblioteca P\u00fablica Central \u201cMargarita Maza de Ju\u00e1rez\u201d<\/li>\n<\/ul>\n<p>Oaxaca de Ju\u00e1rez, Oax., 10 de julio de 2018.- La Secretar\u00eda de la Mujer Oaxaque\u00f1a (SMO), en coordinaci\u00f3n con la Secretar\u00eda de Desarrollo Social y Humano, el Instituto Oaxaque\u00f1o de las Artesan\u00edas y las Instancias Municipales de las Mujeres organiza la Segunda Feria de la Sororidad, a realizarse los d\u00edas 13 y 14 de julio.<\/p>\n<p>En \u00e9sta, m\u00e1s de 60 mujeres artesanas ofertar\u00e1n sus productos en la Biblioteca P\u00fablica Central \u201cMargarita Maza de Ju\u00e1rez\u201d ubicada en la calle Macedonio Alcal\u00e1 n\u00famero 200, esquina Morelos en el centro de la capital de 9:00 a 19:00 horas.<\/p>\n<p>En este contexto, la titular de la SMO, Ana V\u00e1squez Colmenares Guzm\u00e1n destac\u00f3 la importancia de seguir fortaleciendo el proceso de empoderamiento econ\u00f3mico de las mujeres, porque en muchas comunidades de Oaxaca, son ellas quienes mueven la econom\u00eda local con su emprendedurismo, el cual frecuentemente surge ante las adversas circunstancias ocasionadas por la migraci\u00f3n de sus parejas y por la falta de oportunidades en empleos asalariados.<\/p>\n<p>Durante la Segunda Feria de la Sororidad Artesanal se podr\u00e1n adquirir productos de hoja de pino, de palma, barro negro, mezcal, cobijas y tapetes de lana, textiles, talabarter\u00eda y art\u00edculos de piel, bebidas tradicionales de las comunidades, pan de diferentes regiones, filigrana, quesillo org\u00e1nico.<\/p>\n<p>Estar\u00e1n presentes artesanas de San Antonino el Alto, San Lorenzo Cacaotepec, San Bartolom\u00e9 Quialana, Santo Domingo Tonaltepec, Nuevo Zoquiapan, Tlacolula de Matamoros, San Pedro Huiltepec, San Bartolo Coyotepec, Villa Hidalgo Yalalag, San Jer\u00f3nimo Sosola, Santiago Tenango Etla, San Pedro Pochutla, Yanhuitl\u00e1n, San Antonino Castillo Velasco, San Miguel Suchixtepec, Santa Mar\u00eda Alotepec, San Juan del R\u00edo, Tomaltepec, San Bartolom\u00e9 Ayautla, San Juan del Estado, Juchit\u00e1n de Zaragoza, Juquila, Cuicatl\u00e1n, Constancia del Rosario y Santa Mar\u00eda Atzompa.<\/p>\n<p>Es importante considerar que 3 de cada 10 hogares en Oaxaca est\u00e1n encabezados por una mujer y en el caso de las mujeres due\u00f1as de su propia micro empresa, destinan m\u00e1s del 70% de sus ganancias a la comunidad y a su familia.<\/p>\n<p>Por ello, desde la Secretar\u00eda de la Mujer Oaxaque\u00f1a, en sinergia con otras dependencias estatales y federales, se impulsan pol\u00edticas, programas y actividades del sector productivo, orientadas a desarrollar y fortalecer las PyMES creadas por mujeres, fomentando con ello la igualdad de g\u00e9nero y el empoderamiento de las mujeres.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>M\u00e1s de 60 artesanas de todas las regiones ofertar\u00e1n sus productos en la Biblioteca P\u00fablica Central \u201cMargarita Maza de Ju\u00e1rez\u201d Oaxaca de Ju\u00e1rez, Oax., 10 de julio de 2018.- La Secretar\u00eda de la Mujer Oaxaque\u00f1a (SMO), en coordinaci\u00f3n con la Secretar\u00eda de Desarrollo Social y Humano, el Instituto Oaxaque\u00f1o de las Artesan\u00edas y las Instancias [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1938,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7,8],"tags":[],"class_list":["post-1937","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-mostrar-en-la-galeria-principal","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 09:27:10","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/1937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/comments?post=1937"}],"version-history":[{"count":0,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/posts\/1937\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media\/1938"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/media?parent=1937"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/categories?post=1937"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sm\/wp-json\/wp\/v2\/tags?post=1937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}