{"id":8836,"date":"2025-04-08T10:34:32","date_gmt":"2025-04-08T16:34:32","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/sectur\/?p=8836"},"modified":"2025-04-09T10:37:11","modified_gmt":"2025-04-09T16:37:11","slug":"proyecta-sectur-oaxaca-derrama-economica-de-mil-97-mdp-por-temporada-vacacional-en-principales-destinos","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sectur\/proyecta-sectur-oaxaca-derrama-economica-de-mil-97-mdp-por-temporada-vacacional-en-principales-destinos\/","title":{"rendered":"Proyecta Sectur Oaxaca derrama econ\u00f3mica de mil 97 mdp por temporada vacacional en principales destinos"},"content":{"rendered":"<div id=\"\" class=\"su-heading su-heading-style-default su-heading-align-center\">\n<div class=\"su-heading-inner\">\n<hr \/>\n<p>\u2022 Se prev\u00e9 la llegada de m\u00e1s de 234 mil turistas en la temporada de Semana Santa y Pascua a la Ciudad de Oaxaca, Bah\u00edas de Huatulco y Puerto Escondido<\/p>\n<hr \/>\n<\/div>\n<\/div>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax. 8 de abril de 2025.-<\/strong> La Secretar\u00eda de Turismo de Oaxaca informa que durante la pr\u00f3xima temporada vacacional de Semana Santa y Pascua que comprende del 14 al 27 de abril, se espera una derrama econ\u00f3mica de mil 97 millones de pesos en los tres principales destinos de la entidad.<\/p>\n<p>La titular de la dependencia, Saymi Pineda Velasco detall\u00f3 que, en la Ciudad de Oaxaca, Bah\u00edas de Huatulco y Puerto Escondido est\u00e1 prevista una ocupaci\u00f3n hotelera promedio del 72.9 por ciento, y se estima la llegada de 234 mil 301 visitantes nacionales e internacionales.<\/p>\n<p>En este periodo, se prev\u00e9 que en la Ciudad de Oaxaca, la afluencia alcance un total de 93 mil 306 turistas nacionales e internacionales, lo que generar\u00eda una derrama econ\u00f3mica de 385 millones de pesos, y una ocupaci\u00f3n hotelera del 62.61 por ciento.<\/p>\n<p>En la Ruta de la Costa Oaxaque\u00f1a, en el destino de Bah\u00edas de Huatulco, se espera que se reciban a 62 mil 510 turistas, se genere una derrama econ\u00f3mica de 544 millones de pesos y la ocupaci\u00f3n hotelera sea del 86.87 por ciento.<\/p>\n<p>En tanto, para Puerto Escondido las estimaciones indican que 78 mil 485 turistas visiten el destino, lo que estar\u00eda generando una derrama econ\u00f3mica de 168 millones de pesos, con una ocupaci\u00f3n hotelera del 72.71 por ciento.<\/p>\n<p>Pineda Velasco especific\u00f3 que para la temporada de Semana Santa, que comprende del 14 al 20 de abril, se prev\u00e9 que estos tres destinos reciban 118 mil 713 turistas de diversas partes del pa\u00eds y del extranjero, generando ingresos por 586 millones de pesos y una ocupaci\u00f3n hotelera promedio del 78.11 por ciento.<\/p>\n<p>En la semana de Pascua, del 21 al 27 de abril, se espera que estos mismos sitios reciban a 107 mil 639 personas, que dejen una derrama econ\u00f3mica de 511 millones de pesos y ocupaci\u00f3n hotelera del 67.69 por ciento.<\/p>\n<p>De esta manera invita a turistas locales, nacionales e internacionales a disfrutar de las riquezas tur\u00edsticas de la entidad que comprenden: 10 rutas tur\u00edsticas, 6 pueblos m\u00e1gicos y el Barrio M\u00e1gico de Jalatlaco, adem\u00e1s de \u00c1reas Naturales Protegidas, destinos de playa y comunidades ecotur\u00edsticas en las diferentes regiones de la entidad.<\/p>\n<p>Asimismo, exhorta a la poblaci\u00f3n y a las personas turistas a seguir las recomendaciones de seguridad emitidas por cada destino, especialmente en zonas de playa con alto oleaje, evitar ingresar al mar en condiciones que representen un riesgo y mantener bajo supervisi\u00f3n constante a menores de edad para prevenir accidentes.<\/p>\n<p style=\"text-align: center\"><strong>-0-<\/strong><\/p>\n\r\n<div class=\"gdgallery-gallery-container\" id=\"gdgallery-container-97\" data-id=\"97\">\r\n    \r\n\r\n<div id=\"gdgallery_container_97\" style=\"display:none;\" data-view=\"slider\">\r\n\r\n            <img decoding=\"async\" alt=\"\"\r\n             data-type=\"image\"\r\n             src=\"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-content\/uploads\/sites\/65\/2025\/04\/08ABR25-SECTUR-TEMPORADA-VACAIONAL4.jpeg\"\r\n             data-image=\"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-content\/uploads\/sites\/65\/2025\/04\/08ABR25-SECTUR-TEMPORADA-VACAIONAL4.jpeg\"\r\n             data-description=\"\"\r\n                         style=\"display:block\">\r\n\r\n            <img decoding=\"async\" alt=\"\"\r\n             data-type=\"image\"\r\n             src=\"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-content\/uploads\/sites\/65\/2025\/04\/08ABR25-SECTUR-TEMPORADA-VACAIONAL5.jpeg\"\r\n             data-image=\"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-content\/uploads\/sites\/65\/2025\/04\/08ABR25-SECTUR-TEMPORADA-VACAIONAL5.jpeg\"\r\n             data-description=\"\"\r\n                         style=\"display:block\">\r\n\r\n            <img decoding=\"async\" alt=\"\"\r\n             data-type=\"image\"\r\n             src=\"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-content\/uploads\/sites\/65\/2025\/04\/08ABR25-SECTUR-TEMPORADA-VACAIONAL2.jpeg\"\r\n             data-image=\"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-content\/uploads\/sites\/65\/2025\/04\/08ABR25-SECTUR-TEMPORADA-VACAIONAL2.jpeg\"\r\n             data-description=\"\"\r\n                         style=\"display:block\">\r\n\r\n    \r\n<\/div>\r\n\r\n<script type=\"text\/javascript\">\r\n    (function() {\r\n        var runMyCode = function() {\r\n            jQuery(document).ready(function () {\r\n                var container = jQuery(\"#gdgallery_container_97\");\r\n                container.unitegallery({\"gallery_theme\":\"slider\",\"gallery_images_preload_type\":\"minimal\",\"gallery_width\":\"900\",\"gallery_height\":\"500\",\"gallery_autoplay\":true,\"gallery_play_interval\":\"5000\",\"gallery_pause_on_mouseover\":true,\"slider_scale_mode\":\"fill\",\"slider_transition\":\"slide\",\"slider_transition_speed\":1500,\"slider_loader_type\":1,\"slider_loader_color\":\"white\",\"slider_enable_bullets\":true,\"slider_bullets_align_hor\":\"center\",\"slider_bullets_align_vert\":\"bottom\",\"slider_enable_arrows\":true,\"slider_enable_progress_indicator\":true,\"slider_progress_indicator_type\":\"pie\",\"slider_progress_indicator_align_hor\":\"right\",\"slider_progress_indicator_align_vert\":\"top\",\"slider_enable_play_button\":false,\"slider_play_button_align_hor\":\"left\",\"slider_play_button_align_vert\":\"top\",\"slider_enable_fullscreen_button\":false,\"slider_fullscreen_button_align_hor\":\"left\",\"slider_fullscreen_button_align_vert\":\"top\",\"slider_control_zoom\":true,\"slider_enable_zoom_panel\":false,\"slider_zoompanel_align_hor\":\"left\",\"slider_zoompanel_align_vert\":\"top\",\"slider_controls_always_on\":false,\"slider_videoplay_button_type\":\"round\",\"slider_textpanel_always_on\":false,\"slider_enable_text_panel\":true,\"slider_textpanel_enable_title\":true,\"slider_textpanel_enable_description\":true,\"slider_textpanel_enable_bg\":true,\"gallery_carousel\":true,\"slider_textpanel_bg_color\":\"#000000\",\"slider_textpanel_bg_opacity\":0.7,\"slider_textpanel_title_font_size\":\"17\",\"slider_textpanel_title_color\":\"#FFFFFF\",\"slider_textpanel_desc_font_size\":\"14\",\"slider_textpanel_desc_color\":\"#FFFFFF\",\"slider_progress_indicator_offset_hor\":5,\"slider_progress_indicator_offset_vert\":5,\"slider_play_button_offset_hor\":60,\"slider_play_button_offset_vert\":8,\"slider_fullscreen_button_offset_hor\":37,\"slider_fullscreen_button_offset_vert\":9,\"slider_zoompanel_offset_hor\":12,\"slider_zoompanel_offset_vert\":40});\r\n            });\r\n        };\r\n        var timer = function() {\r\n            if (window.jQuery) {runMyCode(window.jQuery);}\r\n            else {window.setTimeout(timer, 100);}\r\n        };\r\n        timer();\r\n    })();\r\n<\/script><style>\r\n\r\n#gdgallery_container_97{margin:0 auto;}<\/style>\r\n<\/div>\r\n\r\n\r\n\r\n\r\n\r\n\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Se prev\u00e9 la llegada de m\u00e1s de 234 mil turistas en la temporada de Semana Santa y Pascua a la Ciudad de Oaxaca, Bah\u00edas de Huatulco y Puerto Escondido<\/p>\n","protected":false},"author":71,"featured_media":8841,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[51,2,5,6,7],"tags":[],"class_list":["post-8836","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-banners","category-boletines","category-destacado","category-slide","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-19 22:20:31","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/posts\/8836","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/comments?post=8836"}],"version-history":[{"count":2,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/posts\/8836\/revisions"}],"predecessor-version":[{"id":8843,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/posts\/8836\/revisions\/8843"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/media\/8841"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/media?parent=8836"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/categories?post=8836"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/tags?post=8836"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}