{"id":8204,"date":"2024-12-11T09:31:10","date_gmt":"2024-12-11T15:31:10","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/sectur\/?p=8204"},"modified":"2024-12-11T09:31:58","modified_gmt":"2024-12-11T15:31:58","slug":"este-10-de-enero-fecha-limite-para-registrar-propuestas-para-la-imagen-oficial-de-la-guelaguetza-2025","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/sectur\/este-10-de-enero-fecha-limite-para-registrar-propuestas-para-la-imagen-oficial-de-la-guelaguetza-2025\/","title":{"rendered":"Este 10 de enero, fecha l\u00edmite para registrar propuestas para la imagen oficial de la Guelaguetza 2025"},"content":{"rendered":"<div align=\"center\">\n<hr \/>\n<p style=\"text-align: left\">\u2022 Las obras participantes deben representar las expresiones art\u00edsticas, folcl\u00f3ricas, danc\u00edsticas, gastron\u00f3micas y tradicionales de las ocho regiones, de sus 16 culturas y el pueblo afromexicano<\/p>\n<hr \/>\n<p style=\"text-align: left\">Oaxaca de Ju\u00e1rez, Oax. 9 de diciembre de 2024.- El Gobierno del Estado a trav\u00e9s de la Secretar\u00eda de Turismo (Sectur) Oaxaca informa que el viernes 10 de enero del 2025 es la fecha l\u00edmite para el registro de las obras de artistas interesados en participar en el concurso para seleccionar la imagen oficial de la Guelaguetza 2025.<\/p>\n<p style=\"text-align: left\">La convocatoria difundida desde el pasado 13 de noviembre est\u00e1 dirigida a oaxaque\u00f1as y oaxaque\u00f1os mayores de 18 a\u00f1os que tengan inter\u00e9s y deseen plasmar una imagen alusiva a esta m\u00e1xima fiesta.<\/p>\n<p style=\"text-align: left\">La titular de la Sectur Oaxaca Saymi Pineda Velasco explic\u00f3 que las obras participantes deben representar las expresiones art\u00edsticas, folcl\u00f3ricas, danc\u00edsticas, gastron\u00f3micas y tradicionales de las ocho regiones del estado, de sus 16 culturas y el pueblo afromexicano.<\/p>\n<p style=\"text-align: left\">La t\u00e9cnica de los trabajos podr\u00e1 ser considerada en las modalidades de pintura acr\u00edlica, acuarela, \u00f3leo, aerograf\u00eda, pintura al pastel, tinta, grabado, t\u00e9cnica mixta, entre otras que se especifican en la convocatoria.<\/p>\n<p style=\"text-align: left\">En esta edici\u00f3n el tema es \u201cGuelaguetza 2025, Fiestas de los Lunes del Cerro\u201d. Las propuestas que se registren deben ser in\u00e9ditas, no haber sido comprometidas para otros eventos, ni exhibidas anteriormente y tampoco participado en otros cert\u00e1menes.<\/p>\n<p style=\"text-align: left\">La recepci\u00f3n de las obras se lleva a cabo en la Secretar\u00eda de Turismo ubicada en la avenida Ju\u00e1rez 703 de la ciudad de Oaxaca de Ju\u00e1rez, y en su momento el jurado calificador, que ser\u00e1 integrado por personas expertas en artes gr\u00e1ficas y organizadoras de las festividades de los Lunes del Cerro, realizar\u00e1 la selecci\u00f3n de la obra ganadora de acuerdo con los lineamientos correspondientes a la t\u00e9cnica, originalidad, composici\u00f3n, creatividad en el manejo de los elementos, materiales y rese\u00f1a o semblanza de la realizaci\u00f3n del trabajo.<\/p>\n<p><strong>-0-<\/strong><\/p>\n<h3><a href=\"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-content\/uploads\/sites\/65\/2024\/11\/CONVOCATORIA-GUELAGUETZA-2025.pdf\">Descargar convocatoria aqu\u00ed<\/a><\/h3>\n<h3><a href=\"http:\/\/www.oaxaca.travel\/images\/convocatoria_guelaguetza_2025.pdf\">Descargar formato de registro aqu\u00ed<\/a><\/h3>\n<\/div>\n<div align=\"center\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-7962\" src=\"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-content\/uploads\/sites\/65\/2024\/11\/CONVOCATORIA-GUELAGUETZA-2025_001-663x1024.jpg\" alt=\"\" width=\"663\" height=\"1024\" srcset=\"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-content\/uploads\/sites\/65\/2024\/11\/CONVOCATORIA-GUELAGUETZA-2025_001-663x1024.jpg 663w, https:\/\/www.oaxaca.gob.mx\/sectur\/wp-content\/uploads\/sites\/65\/2024\/11\/CONVOCATORIA-GUELAGUETZA-2025_001-194x300.jpg 194w, https:\/\/www.oaxaca.gob.mx\/sectur\/wp-content\/uploads\/sites\/65\/2024\/11\/CONVOCATORIA-GUELAGUETZA-2025_001-768x1187.jpg 768w, https:\/\/www.oaxaca.gob.mx\/sectur\/wp-content\/uploads\/sites\/65\/2024\/11\/CONVOCATORIA-GUELAGUETZA-2025_001.jpg 792w\" sizes=\"auto, (max-width: 663px) 100vw, 663px\" \/><\/div>\n","protected":false},"excerpt":{"rendered":"<p>\u2022 Las obras participantes deben representar las expresiones art\u00edsticas, folcl\u00f3ricas, danc\u00edsticas, gastron\u00f3micas y tradicionales de las ocho regiones, de sus 16 culturas y el pueblo afromexicano<\/p>\n","protected":false},"author":71,"featured_media":8206,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[51,2,50,5,6,7],"tags":[],"class_list":["post-8204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-banners","category-boletines","category-convocatorias","category-destacado","category-slide","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:14:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/posts\/8204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/users\/71"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/comments?post=8204"}],"version-history":[{"count":2,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/posts\/8204\/revisions"}],"predecessor-version":[{"id":8208,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/posts\/8204\/revisions\/8208"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/media\/8206"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/media?parent=8204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/categories?post=8204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/sectur\/wp-json\/wp\/v2\/tags?post=8204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}