{"id":173577,"date":"2026-02-16T18:13:01","date_gmt":"2026-02-17T00:13:01","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/?p=173577"},"modified":"2026-02-16T18:13:01","modified_gmt":"2026-02-17T00:13:01","slug":"a-traves-de-oaxaca-segura-y-c5i-sspc-detiene-a-masculino-como-probable-responsable-de-robo-en-la-capital-del-estado","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/a-traves-de-oaxaca-segura-y-c5i-sspc-detiene-a-masculino-como-probable-responsable-de-robo-en-la-capital-del-estado\/","title":{"rendered":"A trav\u00e9s de Oaxaca Segura y C5i, SSPC detiene a masculino como probable responsable de robo en la capital del estado"},"content":{"rendered":"<div class=\"su-heading su-heading-style-default su-heading-align-center\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">\u2022 Esta acci\u00f3n es resultado de la estrecha vigilancia y presencia permanente de las corporaciones estatales en puntos estrat\u00e9gicos de la ciudad<\/div><\/div>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax. 16 de febrero de 2026.-<\/strong> En una acci\u00f3n coordinada que demuestra la eficacia de la estrategia Oaxaca Segura, la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC), a trav\u00e9s de la Polic\u00eda Vial Estatal y con el apoyo tecnol\u00f3gico del C5i Oaxaca, se detuvo a un masculino como probable responsable del delito de robo en la zona de Riberas del R\u00edo Atoyac, en la capital del estado.<\/p>\n<p>En este despliegue operativo, elementos policiacos interceptaron a una persona que se identific\u00f3 como J. C. C., de 40 a\u00f1os, quien fue sorprendido tras el posible hurto de una bater\u00eda de un veh\u00edculo de motor.<\/p>\n<p>Como parte del protocolo, tras la consulta al sistema AFIS (Sistema Automatizado de Identificaci\u00f3n de Huellas Dactilares, por sus siglas en ingl\u00e9s), a trav\u00e9s del Centro de Control, Comando, Comunicaci\u00f3n, Coordinaci\u00f3n e Inteligencia (C5i); arroj\u00f3 que el detenido cuenta con antecedentes por robo y portaci\u00f3n de arma de fuego sin licencia.<\/p>\n<p>Durante la inspecci\u00f3n f\u00edsica, se le localizaron documentos que no pertenecen a su persona, como licencia de conducir y tarjetas bancarias de terceros, lo que presume su participaci\u00f3n en otras actividades il\u00edcitas.<\/p>\n<p>El sujeto y los objetos asegurados fueron puestos a disposici\u00f3n de la Fiscal\u00eda General del Estado de Oaxaca (FGEO) para determinar su situaci\u00f3n jur\u00eddica.<\/p>\n<p>El Gobierno del Estado mantiene estrecha vigilancia y presencia permanente de las corporaciones estatales en puntos estrat\u00e9gicos de la ciudad capital, quienes apoyados por la tecnolog\u00eda; preservan la paz y bienestar en los espacios p\u00fablicos.<\/p>\n<p style=\"text-align: center\"><strong>-0-<\/strong><\/p>\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-16-10 su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-minimal su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a97db918dd0d\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/16FEB26-OAXACASEGURA-DTENCION-819x1024.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/16FEB26-OAXACASEGURA-DTENCION-819x1024.jpeg 819w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/16FEB26-OAXACASEGURA-DTENCION-240x300.jpeg 240w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/16FEB26-OAXACASEGURA-DTENCION-768x960.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/16FEB26-OAXACASEGURA-DTENCION.jpeg 1080w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/div><\/div><\/div><script id=\"su_image_carousel_6a97db918dd0d_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a97db918dd0d\"))}, 0);}var su_image_carousel_6a97db918dd0d_script=document.getElementById(\"su_image_carousel_6a97db918dd0d_script\");if(su_image_carousel_6a97db918dd0d_script){su_image_carousel_6a97db918dd0d_script.parentNode.removeChild(su_image_carousel_6a97db918dd0d_script);}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Oaxaca de Ju\u00e1rez, Oax. 16 de febrero de 2026.- En una acci\u00f3n coordinada que demuestra la eficacia de la estrategia Oaxaca Segura, la Secretar\u00eda de Seguridad y Protecci\u00f3n Ciudadana (SSPC), a trav\u00e9s de la Polic\u00eda Vial Estatal y con el apoyo tecnol\u00f3gico del C5i Oaxaca, se detuvo a un masculino como probable responsable del delito [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":173578,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[8],"tags":[559],"class_list":["post-173577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-sspc"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 02:17:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/comments?post=173577"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173577\/revisions"}],"predecessor-version":[{"id":173579,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173577\/revisions\/173579"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media\/173578"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media?parent=173577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/categories?post=173577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/tags?post=173577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}