{"id":173481,"date":"2026-02-14T15:04:10","date_gmt":"2026-02-14T21:04:10","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/?p=173481"},"modified":"2026-02-14T15:04:10","modified_gmt":"2026-02-14T21:04:10","slug":"recupera-policia-vial-estatal-camioneta-robada-en-san-pedro-mixtepec","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/recupera-policia-vial-estatal-camioneta-robada-en-san-pedro-mixtepec\/","title":{"rendered":"Recupera Polic\u00eda Vial Estatal camioneta robada en San Pedro Mixtepec"},"content":{"rendered":"<p>&nbsp;<\/p>\n<div class=\"su-heading su-heading-style-default su-heading-align-center\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">* La acci\u00f3n fue posible tras el alertamiento del arco Repuve en coordinaci\u00f3n con el C5i<\/div><\/div>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax., 14 de febrero de 2026.-<\/strong> Derivado de un alertamiento emitido por el Centro de Control, Comando, Comunicaci\u00f3n, Coordinaci\u00f3n e Inteligencia (C5i), elementos de la Polic\u00eda Vial Estatal recuperaron una camioneta con reporte de robo vigente.<\/p>\n<p>Los elementos fueron informados sobre la activaci\u00f3n de un arco del Registro P\u00fablico Vehicular (Repuve) en jurisdicci\u00f3n del municipio de San Agust\u00edn de las Juntas, de un veh\u00edculo circulando con incidencia de robo.<\/p>\n<p>Por lo que de inmediato desplegaron un operativo de b\u00fasqueda, localizando la unidad a la altura del crucero del Estadio de Beisbol \u201cEduardo Vasconcelos\u201d, al norte de la ciudad capital, donde procedieron a marcarle el alto y realizar la detenci\u00f3n correspondiente.<\/p>\n<p>La unidad asegurada es una camioneta marca Buick, tipo Avenir, modelo 2024, color azul petr\u00f3leo, con placas de circulaci\u00f3n TKL965A del estado de Oaxaca, misma que fue robada con violencia el pasado 13 de enero en el municipio de San Pedro Mixtepec en la regi\u00f3n Costa.<\/p>\n<p>El conductor fue identificado como J.C.R.C, de 32 a\u00f1os de edad, y junto con la unidad, fueron puestos a disposici\u00f3n de la Fiscal\u00eda General del Estado de Oaxaca para las diligencias correspondientes.<\/p>\n<p>&nbsp;<\/p>\n<p style=\"text-align: center\"><strong>-0-<\/strong><\/p>\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-16-10 su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-minimal su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a97ec82acbee\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"460\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/14FEB26-POLVIAL-CAMIONETA-RECUPERADA-1024x460.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/14FEB26-POLVIAL-CAMIONETA-RECUPERADA-1024x460.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/14FEB26-POLVIAL-CAMIONETA-RECUPERADA-300x135.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/14FEB26-POLVIAL-CAMIONETA-RECUPERADA-768x345.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/14FEB26-POLVIAL-CAMIONETA-RECUPERADA-1536x690.jpeg 1536w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/14FEB26-POLVIAL-CAMIONETA-RECUPERADA.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><script id=\"su_image_carousel_6a97ec82acbee_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a97ec82acbee\"))}, 0);}var su_image_carousel_6a97ec82acbee_script=document.getElementById(\"su_image_carousel_6a97ec82acbee_script\");if(su_image_carousel_6a97ec82acbee_script){su_image_carousel_6a97ec82acbee_script.parentNode.removeChild(su_image_carousel_6a97ec82acbee_script);}<\/script>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Oaxaca de Ju\u00e1rez, Oax., 14 de febrero de 2026.- Derivado de un alertamiento emitido por el Centro de Control, Comando, Comunicaci\u00f3n, Coordinaci\u00f3n e Inteligencia (C5i), elementos de la Polic\u00eda Vial Estatal recuperaron una camioneta con reporte de robo vigente. Los elementos fueron informados sobre la activaci\u00f3n de un arco del Registro P\u00fablico Vehicular (Repuve) [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":173482,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[8],"tags":[2829],"class_list":["post-173481","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-c5i-oaxaca"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 03:29:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173481","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/comments?post=173481"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173481\/revisions"}],"predecessor-version":[{"id":173483,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173481\/revisions\/173483"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media\/173482"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media?parent=173481"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/categories?post=173481"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/tags?post=173481"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}