{"id":173400,"date":"2026-02-13T11:05:56","date_gmt":"2026-02-13T17:05:56","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/?p=173400"},"modified":"2026-02-13T11:05:56","modified_gmt":"2026-02-13T17:05:56","slug":"atestigua-salomon-jara-toma-de-posesion-del-nuevo-comandante-de-coordinacion-de-la-guardia-nacional-en-oaxaca","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/atestigua-salomon-jara-toma-de-posesion-del-nuevo-comandante-de-coordinacion-de-la-guardia-nacional-en-oaxaca\/","title":{"rendered":"Atestigua Salom\u00f3n Jara toma de posesi\u00f3n del nuevo comandante de coordinaci\u00f3n de la Guardia Nacional en Oaxaca"},"content":{"rendered":"<div class=\"su-heading su-heading-style-default su-heading-align-center\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">El Mandatario estatal reconoci\u00f3 la experiencia de Rub\u00e9n Olivares Robles, la cual es determinante para consolidar frutos de paz y justicia para la entidad<\/div><\/div>\n<p><strong>Santa Cruz Xoxocotl\u00e1n, Oax. 13 de febrero de 2026.-<\/strong> El Gobernador Salom\u00f3n Jara Cruz atestigu\u00f3 la ceremonia de posesi\u00f3n de cargo del coronel Rub\u00e9n Olivares Robles, quien a partir del pasado 1 de febrero funge como comandante de la Trig\u00e9simo Octava Coordinaci\u00f3n de la unidad de la Guardia Nacional (GN), ubicada en Santa Cruz Xoxocotl\u00e1n.<\/p>\n<p>En el marco de esta designaci\u00f3n de mando, el titular del Poder Ejecutivo reconoci\u00f3 la experiencia de Olivares Robles, la cual es determinante para fortalecer la coordinaci\u00f3n entre los tres \u00f3rdenes de gobierno y consolidar frutos de paz y justicia para la entidad.<\/p>\n<p>El nuevo coordinador cuenta con distintos cursos dentro del Sistema Educativo Militar, como: formaci\u00f3n de oficiales en el Heroico Colegio Militar, aplicaci\u00f3n de las armas y servicios, mando y estado mayor general, superior de guerra, inicial de formaci\u00f3n y de investigaci\u00f3n policial de la GN.<\/p>\n<p>Asimismo, ha obtenido las promociones en subteniente, teniente, capit\u00e1n segundo, capit\u00e1n primero, mayor, teniente coronel y coronel de caballer\u00eda. Dentro de sus distinciones, el 1 de septiembre de 1997 obtuvo la perseverancia de quinta clase.<\/p>\n<p>Tambi\u00e9n desempe\u00f1\u00f3 los cargos como jefe de la secci\u00f3n de instrucci\u00f3n y operaciones en el cuerpo de cadetes del Heroico Colegio Militar, subjefe del estado mayor en la Vig\u00e9sima Novena Zona Militar, jefe de la Coordinaci\u00f3n Policial Estatal Guerrero, jefe en instrucci\u00f3n en la Escuela Superior de Guerra; as\u00ed como director general de procesamientos de datos aduaneros en la Agencia Nacional de Aduanas.<\/p>\n<p style=\"text-align: center\"><strong>-0-<\/strong><\/p>\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-16-10 su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-minimal su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a98105eb500d\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/ff426abe-810a-43d5-b279-6d510c087297-1024x682.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/ff426abe-810a-43d5-b279-6d510c087297-1024x682.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/ff426abe-810a-43d5-b279-6d510c087297-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/ff426abe-810a-43d5-b279-6d510c087297-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/ff426abe-810a-43d5-b279-6d510c087297-1536x1023.jpeg 1536w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/ff426abe-810a-43d5-b279-6d510c087297.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/992788f5-baee-4a34-8e65-581f0b9a4db0-1024x682.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/992788f5-baee-4a34-8e65-581f0b9a4db0-1024x682.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/992788f5-baee-4a34-8e65-581f0b9a4db0-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/992788f5-baee-4a34-8e65-581f0b9a4db0-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/992788f5-baee-4a34-8e65-581f0b9a4db0-1536x1023.jpeg 1536w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/992788f5-baee-4a34-8e65-581f0b9a4db0.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/1883e7e1-c449-491c-a25c-dbcbdf339ab4-1024x682.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/1883e7e1-c449-491c-a25c-dbcbdf339ab4-1024x682.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/1883e7e1-c449-491c-a25c-dbcbdf339ab4-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/1883e7e1-c449-491c-a25c-dbcbdf339ab4-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/1883e7e1-c449-491c-a25c-dbcbdf339ab4-1536x1023.jpeg 1536w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/1883e7e1-c449-491c-a25c-dbcbdf339ab4.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/94a22634-aa97-47fb-9322-525f24ebaae9-1024x682.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/94a22634-aa97-47fb-9322-525f24ebaae9-1024x682.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/94a22634-aa97-47fb-9322-525f24ebaae9-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/94a22634-aa97-47fb-9322-525f24ebaae9-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/94a22634-aa97-47fb-9322-525f24ebaae9-1536x1023.jpeg 1536w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/94a22634-aa97-47fb-9322-525f24ebaae9.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/3a9c0501-3e37-442f-8a8a-0d71f12dc9c5-1024x682.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/3a9c0501-3e37-442f-8a8a-0d71f12dc9c5-1024x682.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/3a9c0501-3e37-442f-8a8a-0d71f12dc9c5-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/3a9c0501-3e37-442f-8a8a-0d71f12dc9c5-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/3a9c0501-3e37-442f-8a8a-0d71f12dc9c5-1536x1023.jpeg 1536w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/3a9c0501-3e37-442f-8a8a-0d71f12dc9c5.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/2fbc501a-1e3e-4089-9347-dd431f9c3e03-1024x682.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/2fbc501a-1e3e-4089-9347-dd431f9c3e03-1024x682.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/2fbc501a-1e3e-4089-9347-dd431f9c3e03-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/2fbc501a-1e3e-4089-9347-dd431f9c3e03-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/2fbc501a-1e3e-4089-9347-dd431f9c3e03-1536x1023.jpeg 1536w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/2fbc501a-1e3e-4089-9347-dd431f9c3e03.jpeg 1600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/2c1ee927-728c-40a5-8aef-53cf031fb857-1024x683.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/2c1ee927-728c-40a5-8aef-53cf031fb857-1024x683.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/2c1ee927-728c-40a5-8aef-53cf031fb857-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/2c1ee927-728c-40a5-8aef-53cf031fb857-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/2c1ee927-728c-40a5-8aef-53cf031fb857.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><script id=\"su_image_carousel_6a98105eb500d_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a98105eb500d\"))}, 0);}var su_image_carousel_6a98105eb500d_script=document.getElementById(\"su_image_carousel_6a98105eb500d_script\");if(su_image_carousel_6a98105eb500d_script){su_image_carousel_6a98105eb500d_script.parentNode.removeChild(su_image_carousel_6a98105eb500d_script);}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Santa Cruz Xoxocotl\u00e1n, Oax. 13 de febrero de 2026.- El Gobernador Salom\u00f3n Jara Cruz atestigu\u00f3 la ceremonia de posesi\u00f3n de cargo del coronel Rub\u00e9n Olivares Robles, quien a partir del pasado 1 de febrero funge como comandante de la Trig\u00e9simo Octava Coordinaci\u00f3n de la unidad de la Guardia Nacional (GN), ubicada en Santa Cruz Xoxocotl\u00e1n. [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":173402,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7],"tags":[1910],"class_list":["post-173400","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","tag-santa-cruz-xoxocotlan"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 06:02:38","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173400","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/comments?post=173400"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173400\/revisions"}],"predecessor-version":[{"id":173408,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173400\/revisions\/173408"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media\/173402"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media?parent=173400"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/categories?post=173400"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/tags?post=173400"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}