{"id":173350,"date":"2026-02-12T14:26:12","date_gmt":"2026-02-12T20:26:12","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/?p=173350"},"modified":"2026-02-12T14:26:12","modified_gmt":"2026-02-12T20:26:12","slug":"invita-seculta-a-la-12-muestra-de-carnavales-del-estado-de-oaxaca","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/invita-seculta-a-la-12-muestra-de-carnavales-del-estado-de-oaxaca\/","title":{"rendered":"Invita Seculta a la 12\u00b0 Muestra de Carnavales del Estado de Oaxaca"},"content":{"rendered":"<div class=\"su-heading su-heading-style-default su-heading-align-center\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">El Gobierno del Estado contin\u00faa con la difusi\u00f3n, promoci\u00f3n y preservaci\u00f3n de una de las expresiones m\u00e1s representativas del patrimonio cultural inmaterial de la entidad<\/div><\/div>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax. 12 de febrero de 2026.-<\/strong> La Secretar\u00eda de las Culturas y Artes (Seculta) invita a participar en la 12\u00b0 Muestra de Carnavales del Estado de Oaxaca, una celebraci\u00f3n que impulsa la preservaci\u00f3n, difusi\u00f3n y revitalizaci\u00f3n de estas actividades comunitarias.<\/p>\n<p>Las actividades realizadas en coordinaci\u00f3n con el Colectivo de Carnavales de los Valles Centrales, iniciar\u00e1n el viernes 13 de febrero en el Museo de los Pintores Oaxaque\u00f1os (MUPO), con el conversatorio \u201cEl origen de la Muestra de Carnavales en la Ciudad de Oaxaca\u201d a las 15:00 horas.<\/p>\n<p>Posteriormente, a las 17:00 horas y en ese mismo lugar, se entregar\u00e1n galardones a las y los fundadores de esta festividad.<\/p>\n<p>La celebraci\u00f3n central ser\u00e1 el s\u00e1bado 14 de febrero, a partir de las 17:00 horas, con un recorrido que partir\u00e1 del Jard\u00edn Carbajal, avanzar\u00e1 por las calles Macedonio Alcal\u00e1, Jos\u00e9 Mar\u00eda Morelos y concluir\u00e1 en la Plaza de la Danza.<\/p>\n<p>En esta edici\u00f3n participar\u00e1n 11 comunidades y agrupaciones entre ellas: San Mart\u00edn Tilcajete, San Juan Bautista La Raya, Villa de Zaachila, Santa Mar\u00eda Coyotepec, \u00c1nimas Trujano, San Raymundo Jalpan, Heroica Ciudad de Huajuapan de Le\u00f3n, San Juan Juquila Mixes, San Pablo Huitzo, Teotitl\u00e1n del Valle, El Carrizal de Santa Mar\u00eda Pe\u00f1oles y el grupo folcl\u00f3rico Guendabi\u00b4chi.<\/p>\n<p>El Gobierno de Oaxaca contin\u00faa con la difusi\u00f3n, promoci\u00f3n y preservaci\u00f3n de La Muestra de Carnavales, una de las expresiones m\u00e1s representativas del patrimonio cultural inmaterial de Oaxaca.<\/p>\n<p style=\"text-align: center\"><strong>-0-<\/strong><\/p>\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-16-10 su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-minimal su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a98216943a31\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/4ab8289f-92ec-4a10-9d15-ebbc8ec66966-819x1024.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/4ab8289f-92ec-4a10-9d15-ebbc8ec66966-819x1024.jpeg 819w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/4ab8289f-92ec-4a10-9d15-ebbc8ec66966-240x300.jpeg 240w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/4ab8289f-92ec-4a10-9d15-ebbc8ec66966-768x960.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/4ab8289f-92ec-4a10-9d15-ebbc8ec66966-1229x1536.jpeg 1229w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/4ab8289f-92ec-4a10-9d15-ebbc8ec66966.jpeg 1280w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/div><\/div><\/div><script id=\"su_image_carousel_6a98216943a31_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a98216943a31\"))}, 0);}var su_image_carousel_6a98216943a31_script=document.getElementById(\"su_image_carousel_6a98216943a31_script\");if(su_image_carousel_6a98216943a31_script){su_image_carousel_6a98216943a31_script.parentNode.removeChild(su_image_carousel_6a98216943a31_script);}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Oaxaca de Ju\u00e1rez, Oax. 12 de febrero de 2026.- La Secretar\u00eda de las Culturas y Artes (Seculta) invita a participar en la 12\u00b0 Muestra de Carnavales del Estado de Oaxaca, una celebraci\u00f3n que impulsa la preservaci\u00f3n, difusi\u00f3n y revitalizaci\u00f3n de estas actividades comunitarias. Las actividades realizadas en coordinaci\u00f3n con el Colectivo de Carnavales de los [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":173352,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[8],"tags":[371],"class_list":["post-173350","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-seculta"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 07:15:21","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/comments?post=173350"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173350\/revisions"}],"predecessor-version":[{"id":173353,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173350\/revisions\/173353"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media\/173352"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media?parent=173350"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/categories?post=173350"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/tags?post=173350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}