{"id":173328,"date":"2026-02-12T09:46:37","date_gmt":"2026-02-12T15:46:37","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/?p=173328"},"modified":"2026-02-12T09:46:37","modified_gmt":"2026-02-12T15:46:37","slug":"prevaleceran-condiciones-estables-con-cielo-despejado-ambiente-seco-y-aumento-de-calor-en-gran-parte-de-oaxaca-proteccion-civil","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/prevaleceran-condiciones-estables-con-cielo-despejado-ambiente-seco-y-aumento-de-calor-en-gran-parte-de-oaxaca-proteccion-civil\/","title":{"rendered":"Prevalecer\u00e1n condiciones estables con cielo despejado, ambiente seco y aumento de calor en gran parte de Oaxaca: Protecci\u00f3n Civil"},"content":{"rendered":"<div class=\"su-heading su-heading-style-default su-heading-align-center\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">Las temperaturas m\u00e1ximas se registrar\u00e1n en el Istmo de Tehuantepec y Costa, donde se prev\u00e9 brisa fresca hacia el atardecer y oleaje ligeramente elevado<\/div><\/div>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax. 12 de febrero de 2026.-<\/strong> La Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil y Gesti\u00f3n de Riesgos (CEPCyGR) informa que, un flujo anticicl\u00f3nico continuar\u00e1 generando condiciones meteorol\u00f3gicas estables en gran parte del estado, con presencia de calima al amanecer, cielo mayormente despejado, ambiente seco, intensa radiaci\u00f3n solar y aumento progresivo de calor en la tarde.<\/p>\n<p>De acuerdo con el pron\u00f3stico del tiempo emitido por la Comisi\u00f3n Nacional del Agua (Conagua), las temperaturas m\u00e1s bajas se registrar\u00e1n en zonas monta\u00f1osas de la Mixteca y Sierra de Ju\u00e1rez. En contraste, las m\u00e1ximas propiciar\u00e1n un ambiente caluroso, especialmente en el Istmo de Tehuantepec y Costa, donde tambi\u00e9n se prev\u00e9 brisa fresca hacia el atardecer y oleaje ligeramente elevado.<\/p>\n<p>Las temperaturas para este d\u00eda son las siguientes:<\/p>\n<p>\u2022 Valles Centrales, m\u00ednima de 10 y m\u00e1xima de 29 grados<br \/>\n\u2022 Istmo de Tehuantepec, m\u00ednima de 22 y m\u00e1xima de 33 grados<br \/>\n\u2022 Cuenca del Papaloapan, m\u00ednima de 18 y m\u00e1xima de 29 grados<br \/>\n\u2022 Costa, m\u00ednima de 22 y m\u00e1xima de 33 grados<br \/>\n\u2022 Mixteca, m\u00ednima de 9 y m\u00e1xima de 27 grados<br \/>\n\u2022 Sierra de Flores Mag\u00f3n, m\u00ednima de 15 y m\u00e1xima de 30 grados<br \/>\n\u2022 Sierra de Ju\u00e1rez, m\u00ednima de 7 y m\u00e1xima de 24 grados<br \/>\n\u2022 Sierra Sur, m\u00ednima de 8 y m\u00e1xima de 25 grados<\/p>\n<p>Se exhorta a la poblaci\u00f3n atender las recomendaciones de Protecci\u00f3n Civil y Capitan\u00edas de Puerto, as\u00ed como a mantenerse informada de las condiciones meteorol\u00f3gicas a trav\u00e9s de los medios y redes sociales oficiales: Facebook @CEPCYGRGobOax y en X @CEPCyGR_GobOax.<\/p>\n<p style=\"text-align: center\">\n<strong>-0-<\/strong><\/p>\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-16-10 su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-minimal su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a9835a178c44\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/Untitled-1-3.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/Untitled-1-3.jpeg 1000w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/Untitled-1-3-300x225.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/Untitled-1-3-768x576.jpeg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div><\/div><\/div><script id=\"su_image_carousel_6a9835a178c44_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a9835a178c44\"))}, 0);}var su_image_carousel_6a9835a178c44_script=document.getElementById(\"su_image_carousel_6a9835a178c44_script\");if(su_image_carousel_6a9835a178c44_script){su_image_carousel_6a9835a178c44_script.parentNode.removeChild(su_image_carousel_6a9835a178c44_script);}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Oaxaca de Ju\u00e1rez, Oax. 12 de febrero de 2026.- La Coordinaci\u00f3n Estatal de Protecci\u00f3n Civil y Gesti\u00f3n de Riesgos (CEPCyGR) informa que, un flujo anticicl\u00f3nico continuar\u00e1 generando condiciones meteorol\u00f3gicas estables en gran parte del estado, con presencia de calima al amanecer, cielo mayormente despejado, ambiente seco, intensa radiaci\u00f3n solar y aumento progresivo de calor en [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":173329,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[8],"tags":[744],"class_list":["post-173328","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-cepcygr"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 08:41:37","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173328","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/comments?post=173328"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173328\/revisions"}],"predecessor-version":[{"id":173330,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173328\/revisions\/173330"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media\/173329"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media?parent=173328"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/categories?post=173328"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/tags?post=173328"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}