{"id":173312,"date":"2026-02-11T21:28:43","date_gmt":"2026-02-12T03:28:43","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/?p=173312"},"modified":"2026-02-11T21:28:43","modified_gmt":"2026-02-12T03:28:43","slug":"dignifica-salomon-jara-la-casa-de-la-cultura-oaxaquena-espacio-semillero-de-talentos","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/dignifica-salomon-jara-la-casa-de-la-cultura-oaxaquena-espacio-semillero-de-talentos\/","title":{"rendered":"Dignifica Salom\u00f3n Jara la Casa de la Cultura Oaxaque\u00f1a, espacio semillero de talentos"},"content":{"rendered":"<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-16-10 su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-minimal su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a9835b22b853\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/WhatsApp-Image-2026-02-11-at-20.11.05-1024x683.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/WhatsApp-Image-2026-02-11-at-20.11.05-1024x683.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/WhatsApp-Image-2026-02-11-at-20.11.05-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/WhatsApp-Image-2026-02-11-at-20.11.05-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/WhatsApp-Image-2026-02-11-at-20.11.05.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><script id=\"su_image_carousel_6a9835b22b853_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a9835b22b853\"))}, 0);}var su_image_carousel_6a9835b22b853_script=document.getElementById(\"su_image_carousel_6a9835b22b853_script\");if(su_image_carousel_6a9835b22b853_script){su_image_carousel_6a9835b22b853_script.parentNode.removeChild(su_image_carousel_6a9835b22b853_script);}<\/script>\n<div class=\"su-heading su-heading-style-default su-heading-align-center\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">\u2022 El Mandatario estatal entreg\u00f3 la primera etapa de la rehabilitaci\u00f3n de este espacio cultural, que requiri\u00f3 6.4 millones de pesos<\/p>\n<p>\u2022 Tambi\u00e9n dot\u00f3 de instrumentos musicales a 200 agrupaciones de 149 municipios<\/div><\/div>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax. 11 de febrero de 2026.<\/strong> El Gobernador Salom\u00f3n Jara Cruz entreg\u00f3 la primera etapa de la rehabilitaci\u00f3n de la Casa de la Cultura Oaxaque\u00f1a (CCO), como parte del compromiso de su gobierno para mejorar y multiplicar los espacios de fomento, formaci\u00f3n y ense\u00f1anza de las artes.<\/p>\n<p>En este espacio semillero de talento y humanidad, que a lo largo de muchas d\u00e9cadas ha formado a grandes artistas que han llevado el nombre de Oaxaca y M\u00e9xico al mundo, el Mandatario estatal expres\u00f3 que la intervenci\u00f3n realizada, con un monto de 6.4 millones de pesos, es resultado de un trabajo coordinado entre instituciones y del respeto al patrimonio.<\/p>\n<p>\u201cEn Oaxaca la cultura no se abandona ni se improvisa, se cuida, se impulsa y se pone al centro del pueblo, porque un pueblo que defiende su cultura es un pueblo con identidad, con memoria y con esperanza\u201d, afirm\u00f3 en este acto, en el que tambi\u00e9n entreg\u00f3 892 instrumentos musicales a 200 agrupaciones de 149 municipios, que requiri\u00f3 una inversi\u00f3n de 36.8 millones de pesos.<\/p>\n<p>La dignificaci\u00f3n del inmueble estuvo a cargo del Instituto del Patrimonio Cultural del Estado (Inpac), en coordinaci\u00f3n con el Instituto Nacional de Antropolog\u00eda e Historia (INAH), con el fin de mejorar las condiciones f\u00edsicas para ofrecer espacios adecuados, seguros y accesibles para las actividades culturales que aqu\u00ed se desarrollan.<\/p>\n<p>En su oportunidad, la directora de la CCO, Sara Carolina Orozco Mart\u00ednez expres\u00f3 que para el Gobierno de la Primavera Oaxaque\u00f1a la cultura es motor de transformaci\u00f3n, y con acciones como esta se fortalece el tejido social y se consolida un Oaxaca m\u00e1s incluyente, m\u00e1s humano y profundamente orgulloso de su herencia.<\/p>\n<p>\u201cEst\u00e1 demostrado que Oaxaca avanza cuando su historia se honra, y su gente es puesta en el centro de las decisiones\u201d, dijo, al tiempo de agradecer las labores realizadas en beneficio de quienes acuden a los talleres que se imparten.<\/p>\n<p>Asimismo, la directora general del Inpac, Sildia Mecott G\u00f3mez expres\u00f3 que la intervenci\u00f3n se realiz\u00f3, escuchando las necesidades de las personas usuarias, sin perder la esencia que hace a este espacio un lugar creativo.<\/p>\n<p>\u201cEsta obra forma parte de una visi\u00f3n m\u00e1s amplia que hoy impulsa el Gobierno del del Estado a trav\u00e9s de las Obras Primavera del Patrimonio Cultural, acciones que atienden necesidades reales de infraestructura, mantenimiento y servicio, entendiendo que preservar nuestros espacios culturales no es un lujo, sino una responsabilidad con nuestra historia y con las nuevas generaciones\u201d, asever\u00f3.<\/p>\n<p>Las acciones incluyeron el dise\u00f1\u00f3 una nueva estructura retr\u00e1ctil con cubierta de lona en el segundo patio, que permitir\u00e1 abrirse o cerrarse seg\u00fan las necesidades; el aprovechamiento de los pasillos de la planta alta que ampl\u00edan las oportunidades para talleres y cursos; as\u00ed como la intervenci\u00f3n del n\u00facleo sanitario en este piso.<\/p>\n<p>Tambi\u00e9n se tech\u00f3 el pasillo perif\u00e9rico, se rehabilit\u00f3 la iluminaci\u00f3n, se dio mantenimiento a la viguer\u00eda de madera y se realizaron trabajos generales de pintura.<\/p>\n<p style=\"text-align: center\">\n<strong>-0-<\/strong><\/p>\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-16-10 su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-minimal su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a9835b22c0af\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-3-1024x683.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-3-1024x683.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-3-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-3-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-3.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-4-1024x683.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-4-1024x683.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-4-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-4-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-4.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-1-1024x683.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-1-1024x683.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-1-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-1-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-1.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-2-1024x683.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-2-1024x683.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-2-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-2-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/11FEB26-GOB-CCO-2.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><script id=\"su_image_carousel_6a9835b22c0af_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a9835b22c0af\"))}, 0);}var su_image_carousel_6a9835b22c0af_script=document.getElementById(\"su_image_carousel_6a9835b22c0af_script\");if(su_image_carousel_6a9835b22c0af_script){su_image_carousel_6a9835b22c0af_script.parentNode.removeChild(su_image_carousel_6a9835b22c0af_script);}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Oaxaca de Ju\u00e1rez, Oax. 11 de febrero de 2026. El Gobernador Salom\u00f3n Jara Cruz entreg\u00f3 la primera etapa de la rehabilitaci\u00f3n de la Casa de la Cultura Oaxaque\u00f1a (CCO), como parte del compromiso de su gobierno para mejorar y multiplicar los espacios de fomento, formaci\u00f3n y ense\u00f1anza de las artes. En este espacio semillero de [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":173314,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[7],"tags":[74],"class_list":["post-173312","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-slide","tag-cco"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 08:41:54","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173312","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/comments?post=173312"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173312\/revisions"}],"predecessor-version":[{"id":173318,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173312\/revisions\/173318"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media\/173314"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media?parent=173312"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/categories?post=173312"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/tags?post=173312"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}