{"id":173276,"date":"2026-02-11T15:14:02","date_gmt":"2026-02-11T21:14:02","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/?p=173276"},"modified":"2026-02-11T15:14:02","modified_gmt":"2026-02-11T21:14:02","slug":"brinda-gobierno-de-oaxaca-100-de-estimulo-fiscal-en-el-registro-extemporaneo-de-mayores-de-18-anos-y-binacionalidad","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/brinda-gobierno-de-oaxaca-100-de-estimulo-fiscal-en-el-registro-extemporaneo-de-mayores-de-18-anos-y-binacionalidad\/","title":{"rendered":"Brinda Gobierno de Oaxaca 100% de est\u00edmulo fiscal en el registro extempor\u00e1neo de mayores de 18 a\u00f1os y binacionalidad"},"content":{"rendered":"<div class=\"su-heading su-heading-style-default su-heading-align-center\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">Ambos tr\u00e1mites pueden realizarse en las Oficial\u00edas del Registro Civil ubicadas en las ocho regiones del estado<\/div><\/div>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax. 11 de febrero de 2026.-<\/strong> La Direcci\u00f3n del Registro Civil informa que durante todo el a\u00f1o 2026, los tr\u00e1mites de registro extempor\u00e1neo para personas mayores de 18 a\u00f1os e inserci\u00f3n del acta de nacimiento para hijas e hijos de mexicanos nacidos en el extranjero, tendr\u00e1n un 100 por ciento de est\u00edmulo fiscal.<\/p>\n<p>El director de la dependencia, Alfredo Santiago Ch\u00e1vez se\u00f1al\u00f3 que estas acciones representan un paso firme para acercar los servicios a la poblaci\u00f3n que hist\u00f3ricamente ha enfrentado obst\u00e1culos administrativos o econ\u00f3micos para regularizar su identidad.<\/p>\n<div class=\"su-quote su-quote-style-default\"><div class=\"su-quote-inner su-u-clearfix su-u-trim\">\u201cLa identidad es un derecho humano fundamental; con estas medidas, el Gobierno del Estado atiende a las y los oaxaque\u00f1os, elimina costos y simplifica procesos para que nadie se quede sin su acta de nacimiento\u201d, expres\u00f3.<\/div><\/div>\n<p>Ambos tr\u00e1mites pueden realizarse en las Oficial\u00edas del Registro Civil ubicadas en las ocho regiones del estado.<\/p>\n<p>Para el acta de binacionalidad es necesaria la solicitud firmada, acta de nacimiento original foliada del pa\u00eds de origen, actas de nacimiento de madre y\/o padre, identificaci\u00f3n oficial con fotograf\u00eda de la persona solicitante y comprobante de domicilio.<\/p>\n<p>La expedici\u00f3n de un acta extempor\u00e1nea requiere la comparecencia f\u00edsica de la persona a registrar y la presentaci\u00f3n de la solicitud conforme al formato autorizado por la Direcci\u00f3n del Registro Civil.<\/p>\n<p>Asimismo, se tendr\u00e1 que entregar la constancia emitida por la autoridad municipal que d\u00e9 fe de las circunstancias del nacimiento, documentos p\u00fablicos o privados que acrediten el uso del nombre con el que se pretende registrar la persona.<\/p>\n<p>Tambi\u00e9n se solicita la presencia de las personas progenitoras o persona distinta con su respectiva acta de nacimiento, e identificaci\u00f3n oficial con fotograf\u00eda vigente.<\/p>\n<p style=\"text-align: center\"><strong>-0-<\/strong><\/p>\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-16-10 su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-minimal su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a984985969b0\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"682\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/cbe2ef50-6668-461e-bcb2-ca110f1bdbee-1024x682.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/cbe2ef50-6668-461e-bcb2-ca110f1bdbee-1024x682.jpeg 1024w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/cbe2ef50-6668-461e-bcb2-ca110f1bdbee-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/cbe2ef50-6668-461e-bcb2-ca110f1bdbee-768x512.jpeg 768w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/cbe2ef50-6668-461e-bcb2-ca110f1bdbee.jpeg 1280w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><\/div><script id=\"su_image_carousel_6a984985969b0_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a984985969b0\"))}, 0);}var su_image_carousel_6a984985969b0_script=document.getElementById(\"su_image_carousel_6a984985969b0_script\");if(su_image_carousel_6a984985969b0_script){su_image_carousel_6a984985969b0_script.parentNode.removeChild(su_image_carousel_6a984985969b0_script);}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Oaxaca de Ju\u00e1rez, Oax. 11 de febrero de 2026.- La Direcci\u00f3n del Registro Civil informa que durante todo el a\u00f1o 2026, los tr\u00e1mites de registro extempor\u00e1neo para personas mayores de 18 a\u00f1os e inserci\u00f3n del acta de nacimiento para hijas e hijos de mexicanos nacidos en el extranjero, tendr\u00e1n un 100 por ciento de est\u00edmulo [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":173277,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[8],"tags":[346],"class_list":["post-173276","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-registro-civil"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 10:06:29","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173276","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/comments?post=173276"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173276\/revisions"}],"predecessor-version":[{"id":173278,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173276\/revisions\/173278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media\/173277"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media?parent=173276"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/categories?post=173276"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/tags?post=173276"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}