{"id":173226,"date":"2026-02-11T10:06:44","date_gmt":"2026-02-11T16:06:44","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/?p=173226"},"modified":"2026-02-11T10:06:44","modified_gmt":"2026-02-11T16:06:44","slug":"invita-secretaria-de-administracion-a-jornada-gratuita-de-deteccion-y-prevencion-de-infecciones-de-transmision-sexual","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/invita-secretaria-de-administracion-a-jornada-gratuita-de-deteccion-y-prevencion-de-infecciones-de-transmision-sexual\/","title":{"rendered":"Invita Secretar\u00eda de Administraci\u00f3n a jornada gratuita de detecci\u00f3n y prevenci\u00f3n de Infecciones de Transmisi\u00f3n Sexual"},"content":{"rendered":"<div class=\"su-heading su-heading-style-default su-heading-align-center\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">Se desarrollar\u00e1 el pr\u00f3ximo viernes 13 de febrero en la Oficina de Convenciones, Congresos y Eventos de Oaxaca; en un horario de 9:00 a 14:00 horas<\/div><\/div>\n<p><strong>Oaxaca de Ju\u00e1rez, Oax. 11 de febrero de 2026.-<\/strong> La Secretar\u00eda de Administraci\u00f3n (SA), a trav\u00e9s del centro Mujer Tu Espacio, realizar\u00e1 este viernes 13 de febrero actividades gratuitas orientadas a la promoci\u00f3n de la salud y prevenci\u00f3n de Infecciones de Transmisi\u00f3n Sexual, en la Oficina de Convenciones, Congresos y Eventos de Oaxaca (OCCE).<\/p>\n<p>Como parte de esta programaci\u00f3n, a las 10:00 horas se impartir\u00e1 la ponencia \u201cProfilaxis para la prevenci\u00f3n del VIH: PEP y PrEP\u201d, en el sal\u00f3n Mazateco; adem\u00e1s, se llevar\u00e1 a cabo la \u201cJornada 2026 de detecci\u00f3n de VIH, S\u00edfilis y Hepatitis C\u201d, que brindar\u00e1 pruebas r\u00e1pidas a personas mayores de edad, en el estacionamiento del mismo recinto, en un horario de 9:00 a 14:00 horas.<\/p>\n<p>Para acceder a dichas pruebas, las y los interesados deber\u00e1n presentar su Clave \u00danica de Registro de Poblaci\u00f3n (CURP) y Registro Federal de Contribuyentes (RFC).<\/p>\n<p>El Gobierno del Estado impulsa acciones preventivas para contribuir al bienestar y salud de la poblaci\u00f3n oaxaque\u00f1a.<\/p>\n<p style=\"text-align: center\"><strong>-0-<\/strong><\/p>\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-16-10 su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-minimal su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a986f4fb65ce\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"480\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/9c75b040-595b-449d-9beb-7569f7cce178.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/9c75b040-595b-449d-9beb-7569f7cce178.jpeg 720w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/9c75b040-595b-449d-9beb-7569f7cce178-300x200.jpeg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"405\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/c4c437e3-c5fd-4c0d-81b1-73b04f1c2336.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/c4c437e3-c5fd-4c0d-81b1-73b04f1c2336.jpeg 720w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2026\/02\/c4c437e3-c5fd-4c0d-81b1-73b04f1c2336-300x169.jpeg 300w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><\/div><\/div><\/div><script id=\"su_image_carousel_6a986f4fb65ce_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a986f4fb65ce\"))}, 0);}var su_image_carousel_6a986f4fb65ce_script=document.getElementById(\"su_image_carousel_6a986f4fb65ce_script\");if(su_image_carousel_6a986f4fb65ce_script){su_image_carousel_6a986f4fb65ce_script.parentNode.removeChild(su_image_carousel_6a986f4fb65ce_script);}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Oaxaca de Ju\u00e1rez, Oax. 11 de febrero de 2026.- La Secretar\u00eda de Administraci\u00f3n (SA), a trav\u00e9s del centro Mujer Tu Espacio, realizar\u00e1 este viernes 13 de febrero actividades gratuitas orientadas a la promoci\u00f3n de la salud y prevenci\u00f3n de Infecciones de Transmisi\u00f3n Sexual, en la Oficina de Convenciones, Congresos y Eventos de Oaxaca (OCCE). Como [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":173228,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[8],"tags":[354],"class_list":["post-173226","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-sa"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-09-09 12:47:43","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/comments?post=173226"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173226\/revisions"}],"predecessor-version":[{"id":173229,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/173226\/revisions\/173229"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media\/173228"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media?parent=173226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/categories?post=173226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/tags?post=173226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}