{"id":14577,"date":"2018-03-23T18:46:39","date_gmt":"2018-03-24T00:46:39","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/?p=14577"},"modified":"2018-03-23T18:46:39","modified_gmt":"2018-03-24T00:46:39","slug":"registra-oaxaca-764-casos-nuevos-de-tuberculosis-al-ano","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/registra-oaxaca-764-casos-nuevos-de-tuberculosis-al-ano\/","title":{"rendered":"Registra Oaxaca 764 casos nuevos de tuberculosis al a\u00f1o"},"content":{"rendered":"<ul>\n<li>\n<p>Hace 136 a\u00f1os -1882- que Roberto Koch detecto\u0301 la bacteria que causa la Tuberculosis.<\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><strong>Oaxaca de Ju\u00e1rez, Oax., 23 de marzo de 2018.<\/strong>\u00a0A nivel mundial, un tercio de la poblaci\u00f3n se encuentra infectada por la tuberculosis (TB) y cifras de la Organizaci\u00f3n Mundial de la Salud (OMS), calculan que en 2016 hubo 10.4 millones de casos nuevos, causando la muerte de 1.3 millones de personas, entre ellas 374 mil asociadas con el Virus de Inmunodeficiencia Humana (VIH).<\/p>\n<p>La Directora de Prevenci\u00f3n y Promoci\u00f3n de los Servicios de Salud de Oaxaca (SSO), Mar\u00eda del Pilar Nava Ram\u00edrez se\u00f1al\u00f3 que esta enfermedad es un problema de salud p\u00fablica en todo el mundo, y es causada por una bacteria (Mycobacterium tuberculosis), que afecta los pulmones.<\/p>\n<p>En el marco del D\u00eda Mundial de lucha contra la Tuberculosis -que se celebra el 24 de marzo- dijo que es inter\u00e9s de la actual administraci\u00f3n que encabeza el Gobernador Alejandro Murat Hinojosa y el encargado del Despacho de los SSO, Donato Casas Escamilla, realizar la detecci\u00f3n y tratamiento oportuno en las unidades de primer nivel.<\/p>\n<p>Dijo que la instituci\u00f3n realiza jornadas de b\u00fasqueda intensiva de casos en aquellas personas que presenten tos con flemas por m\u00e1s de 15 d\u00edas, fiebre vespertina, falta de apetito, p\u00e9rdida de peso y sudoraciones nocturnas.<\/p>\n<p>Detall\u00f3 que la forma de contagio es de una persona enferma quien al toser, estornudar o hablar arroja gotitas de saliva con la bacteria, las cuales quedan suspendidas en el aire y al respirarlas se van a los pulmones, infectando a las personas.<\/p>\n<p>Inform\u00f3 que Oaxaca ocupa el lugar n\u00famero 15 con una tasa de 18.8 por arriba de la media nacional, con 764 casos nuevos de Tuberculosis en todas las formas (TBTF); de los cuales el 60.7 por ciento son varones y el 39.3 por ciento son mujeres, siendo las regiones de Tuxtepec, Valles Centrales e Istmo las m\u00e1s afectadas.<\/p>\n<p>Enfatiz\u00f3 que un paciente con TB pulmonar que no recibe tratamiento puede infectar de 10 a 15 personas en el transcurso de un solo a\u00f1o y de un 5 a 10 por ciento de los infectados pueden desarrollar la enfermedad en alg\u00fan momento de sus vidas.<\/p>\n<p>La funcionaria dijo que el riesgo es mayor ante la presencia de enfermedades como Diabetes Mellitus y VIH. As\u00ed mismo la desnutrici\u00f3n, alcoholismo, condiciones de vulnerabilidad como son las personas privadas de su libertad, migrantes, jornaleros agr\u00edcolas incrementan el riesgo de padecer TB.<\/p>\n<p>Finalmente, sostuvo que de acuerdo a la Organizaci\u00f3n Panamericana de la Salud (OPS), M\u00e9xico ocupa el tercer lugar con casos de Tuberculosis en todas sus formas, despu\u00e9s de Brasil y Per\u00fa. Ante ello se\u00f1al\u00f3 que la tuberculosis es curable si se detecta a tiempo, por lo que exhort\u00f3 a la poblaci\u00f3n a acudir a su unidad de salud m\u00e1s cercana si presenta los s\u00edntomas antes mencionados.<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;\t\t<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace 136 a\u00f1os -1882- que Roberto Koch detecto\u0301 la bacteria que causa la Tuberculosis. \u00a0Oaxaca de Ju\u00e1rez, Oax., 23 de marzo de 2018.\u00a0A nivel mundial, un tercio de la poblaci\u00f3n se encuentra infectada por la tuberculosis (TB) y cifras de la Organizaci\u00f3n Mundial de la Salud (OMS), calculan que en 2016 hubo 10.4 millones de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[8],"tags":[419],"class_list":["post-14577","post","type-post","status-publish","format-standard","hentry","category-noticias","tag-sso"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 01:16:06","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/14577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/comments?post=14577"}],"version-history":[{"count":0,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/14577\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media?parent=14577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/categories?post=14577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/tags?post=14577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}