{"id":129065,"date":"2024-07-14T16:49:21","date_gmt":"2024-07-14T22:49:21","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/?p=129065"},"modified":"2024-07-14T19:23:55","modified_gmt":"2024-07-15T01:23:55","slug":"invita-sso-a-expo-salud-en-santa-maria-guienagati","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/invita-sso-a-expo-salud-en-santa-maria-guienagati\/","title":{"rendered":"Invita SSO a Expo Salud en Santa Mar\u00eda Guienagati"},"content":{"rendered":"<div class=\"su-heading su-heading-style-default su-heading-align-center\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">El evento gratuito se llevar\u00e1 a cabo el 16 de julio, a partir de las 9:00 horas<\/div><\/div>\n<div class=\"su-heading su-heading-style-default su-heading-align-center\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">Se complementar\u00e1n esquemas de vacunaci\u00f3n en todo el municipio<\/div><\/div>\n<p><strong>Santa Mar\u00eda Guienagati, Oax. 14 de julio de 2024.-<\/strong> Los Servicios de Salud de Oaxaca (SSO) a trav\u00e9s de la Jurisdicci\u00f3n Sanitaria 2 Istmo, invitan a la poblaci\u00f3n a participar en la \u201cExpo Salud en tu Comunidad\u201d, que se llevar\u00e1 a cabo este martes 16 de julio, a partir de las 9:00 horas, en el domo municipal de Santa Mar\u00eda Guienagati.<\/p>\n<p>Una de las prioridades de la administraci\u00f3n actual es elevar la calidad de vida de las personas, por tal motivo se crean de manera decidida iniciativas que buscan fomentar estilos de vida saludables y medidas preventivas, a fin de contribuir en el bienestar de las familias de las comunidades en la entidad.<\/p>\n<p>Dicha acci\u00f3n se realizar\u00e1 en coordinaci\u00f3n con el Ayuntamiento Municipal para acercar a la poblaci\u00f3n diferentes servicios integrales para todos los grupos de edad, de manera gratuita, enfocados en la prevenci\u00f3n, detecci\u00f3n y atenci\u00f3n de patolog\u00edas m\u00e1s comunes.<\/p>\n<p>Se brindar\u00e1n consultas de medicina general; de odontolog\u00eda con atenci\u00f3n preventiva, curativa y prevenci\u00f3n de enfermedades bucodentales; toma de Papanicolaou; exploraci\u00f3n cl\u00ednica de mama para detecci\u00f3n oportuna de c\u00e1ncer mamario, y con base al programa de Salud Sexual y Reproductiva se aplicar\u00e1n implantes subd\u00e9rmicos anticonceptivos.<\/p>\n<p>Tambi\u00e9n se ofrecer\u00e1n pruebas r\u00e1pidas de VIH y hepatitis; y se llevar\u00e1n a cabo detecciones de diabetes mellitus, hipertensi\u00f3n arterial y orientaci\u00f3n nutricional mediante el personal de la Unidad de Especialidades M\u00e9dicas en Enfermedades Cr\u00f3nicas (UNEME EC) de Santo Domingo Tehuantepec.<\/p>\n<p>Aunado a ello, se ofertar\u00e1n pl\u00e1ticas de orientaci\u00f3n y consejer\u00eda para prevenci\u00f3n de enfermedades, y el Centro Comunitario de Salud Mental y Adiciones (Cecosama) brindar\u00e1 informaci\u00f3n para la prevenci\u00f3n, promoci\u00f3n y atenci\u00f3n a los problemas de salud mental y consumo de sustancias psicoactivas como el tabaco, alcohol y otras drogas, adem\u00e1s de atenci\u00f3n para la prevenci\u00f3n del suicidio.<\/p>\n<p>Tambi\u00e9n se aplicar\u00e1n vacunas antirr\u00e1bicas y se brindar\u00e1 el servicio de esterilizaci\u00f3n canina y felina; se proporcionar\u00e1 el desparasitante albendazol, Vida Suero Oral (VSO), y plata coloidal para desinfectar verduras, frutas y agua para consumo humano.<\/p>\n<p>Personal del programa Vectores realizar\u00e1 toma de gota gruesa para detecci\u00f3n de Paludismo a personas usuarias que presenten s\u00edntomas de la enfermedad. En atenci\u00f3n y prevenci\u00f3n del dengue se distribuir\u00e1 larvicida para control larvario, as\u00ed como la nebulizaci\u00f3n y termonebulizaci\u00f3n a toda la localidad, adem\u00e1s del rociado residual (intradomiciliario) a casos probables.<\/p>\n<p>Los SSO indicaron que el personal del programa de Vacunaci\u00f3n Universal acudir\u00e1 el 15 y 16 de julio para completar esquemas de vacunaci\u00f3n y aplicaci\u00f3n de biol\u00f3gicos contra t\u00e9tanos (Td), tuberculosis (BCG), rotavirus, sarampi\u00f3n, rub\u00e9ola y parotiditis (SRP), difteria, t\u00e9tanos, tosferina, hepatitis B, Haemophilus influenzae B y poliomielitis (Hexavalente), as\u00ed como para la prevenci\u00f3n de t\u00e9tanos, difteria y tosferina con la dosis de Tdpa.<\/p>\n<p>La dependencia establece estrategias para mejorar la calidad de vida de las y los habitantes, acercando acciones en salud p\u00fablica con un trato m\u00e1s cercano, amable y humano para orientar a la poblaci\u00f3n en el cuidado de la salud f\u00edsica y mental.<\/p>\n<p style=\"text-align: center\"><strong>-0-<\/strong><\/p>\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-21-9 su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-photo su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a04a94ecd689\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"416\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/07\/14JUL24-SSO-EXPOSALUD-1.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/07\/14JUL24-SSO-EXPOSALUD-1.jpeg 740w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/07\/14JUL24-SSO-EXPOSALUD-1-300x169.jpeg 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"555\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/07\/14JUL24-SSO-EXPOSALUD-2.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/07\/14JUL24-SSO-EXPOSALUD-2.jpeg 740w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/07\/14JUL24-SSO-EXPOSALUD-2-300x225.jpeg 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"416\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/07\/14JUL24-SSO-EXPOSALUD-3.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/07\/14JUL24-SSO-EXPOSALUD-3.jpeg 740w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/07\/14JUL24-SSO-EXPOSALUD-3-300x169.jpeg 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"740\" height=\"416\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/07\/14JUL24-SSO-EXPOSALUD-4.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/07\/14JUL24-SSO-EXPOSALUD-4.jpeg 740w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/07\/14JUL24-SSO-EXPOSALUD-4-300x169.jpeg 300w\" sizes=\"auto, (max-width: 740px) 100vw, 740px\" \/><\/div><\/div><\/div><script id=\"su_image_carousel_6a04a94ecd689_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a04a94ecd689\"))}, 0);}var su_image_carousel_6a04a94ecd689_script=document.getElementById(\"su_image_carousel_6a04a94ecd689_script\");if(su_image_carousel_6a04a94ecd689_script){su_image_carousel_6a04a94ecd689_script.parentNode.removeChild(su_image_carousel_6a04a94ecd689_script);}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Santa Mar\u00eda Guienagati, Oax. 14 de julio de 2024.- Los Servicios de Salud de Oaxaca (SSO) a trav\u00e9s de la Jurisdicci\u00f3n Sanitaria 2 Istmo, invitan a la poblaci\u00f3n a participar en la \u201cExpo Salud en tu Comunidad\u201d, que se llevar\u00e1 a cabo este martes 16 de julio, a partir de las 9:00 horas, en el [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":129069,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[8],"tags":[419],"class_list":["post-129065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-sso"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 10:39:42","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/129065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/comments?post=129065"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/129065\/revisions"}],"predecessor-version":[{"id":129070,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/129065\/revisions\/129070"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media\/129069"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media?parent=129065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/categories?post=129065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/tags?post=129065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}