{"id":120942,"date":"2024-02-29T10:00:45","date_gmt":"2024-02-29T16:00:45","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/?p=120942"},"modified":"2024-02-29T10:00:45","modified_gmt":"2024-02-29T16:00:45","slug":"pone-en-marcha-coesfo-plan-de-combate-de-incendio-en-san-lucas-quiavini","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/pone-en-marcha-coesfo-plan-de-combate-de-incendio-en-san-lucas-quiavini\/","title":{"rendered":"Pone en marcha Coesfo plan de combate de incendio en San Lucas Quiavin\u00ed"},"content":{"rendered":"<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-21-9 su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-photo su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a577e12606e2\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"742\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-1.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-1.jpeg 990w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-1-300x225.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-1-768x576.jpeg 768w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/div><\/div><\/div><script id=\"su_image_carousel_6a577e12606e2_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a577e12606e2\"))}, 0);}var su_image_carousel_6a577e12606e2_script=document.getElementById(\"su_image_carousel_6a577e12606e2_script\");if(su_image_carousel_6a577e12606e2_script){su_image_carousel_6a577e12606e2_script.parentNode.removeChild(su_image_carousel_6a577e12606e2_script);}<\/script>\n<p aria-hidden=\"true\">\n<div class=\"su-heading su-heading-style-default su-heading-align-center\" id=\"\" style=\"font-size:13px;margin-bottom:20px\"><div class=\"su-heading-inner\">La ma\u00f1ana de este jueves se realiz\u00f3 un sobrevuelo en la zona a trav\u00e9s de una aeronave de la Direcci\u00f3n General del Hangar Oficial del Gobierno del Estado para ubicar los principales frentes activos<\/div><\/div>\n<p aria-hidden=\"true\">\n<p><strong>Oaxaca de Ju\u00e1rez, Oax. 29 de febrero de 2024<\/strong>. Ante el incendio registrado en el municipio de San Lucas Quiavin\u00ed, se estableci\u00f3 un plan de combate a trav\u00e9s de personal t\u00e9cnico de la Comisi\u00f3n Estatal Forestal (Coesfo), la Comisi\u00f3n Nacional Forestal (Conafor) y personal de Protecci\u00f3n Civil de Tlacolula de Matamoros y de San Pablo Villa de Mitla.<\/p>\n<p>En esta estrategia participan tambi\u00e9n autoridades municipales y ejidales de la comunidad para salvaguardar la integridad de las personas voluntarias que realizan labores de combate en la zona afectada.<\/p>\n<p>Se inform\u00f3 que en el lugar ya se encuentran brigadas de personal combatiente de la Coesfo provenientes de San Isidro Huay\u00e1pam y El Tequio Xoxocotl\u00e1n, quienes se coordinan con elementos combatientes de la Conafor y personas voluntarias de esta localidad.<\/p>\n<p>Este plan de combate inici\u00f3 este jueves con un sobrevuelo en la zona a trav\u00e9s de una aeronave de la Direcci\u00f3n General del Hangar Oficial del Gobierno del Estado para ubicar los principales frentes activos de este incendio y llevar a cabo acciones de combate, control y liquidaci\u00f3n, mediante la cooperaci\u00f3n de los tres \u00f3rdenes de gobierno que coordinar\u00e1n las labores a realizarse con el apoyo de alrededor de 200 personas voluntarias, comuneros y autoridades.<\/p>\n<p>Lo anterior, para atacar de forma efectiva y segura los frentes activos presentes en este incendio y con ello, evitar poner en riesgo a la poblaci\u00f3n, as\u00ed como a la flora y fauna que habita en esta zona.<\/p>\n<p>Toda vez que se aproxima la temporada de estiaje, la Comisi\u00f3n Estatal Forestal invita a la poblaci\u00f3n en general evitar hacer uso de fuego cerca de zonas con cobertura forestal y vegetal, y en caso de ser necesario reportar incendios forestales a los n\u00fameros 951 516 5112, 951 503 2537, 951 503 2166 o al 9-1-1.<\/p>\n<p style=\"text-align: center\"><strong>\u00a0-0-<\/strong><\/p>\n<div class=\"su-image-carousel  su-image-carousel-has-spacing su-image-carousel-crop su-image-carousel-crop-16-10 su-image-carousel-has-outline su-image-carousel-adaptive su-image-carousel-slides-style-photo su-image-carousel-controls-style-dark su-image-carousel-align-center\" style=\"\" data-flickity-options='{\"groupCells\":true,\"cellSelector\":\".su-image-carousel-item\",\"adaptiveHeight\":false,\"cellAlign\":\"left\",\"prevNextButtons\":true,\"pageDots\":true,\"autoPlay\":5000,\"imagesLoaded\":true,\"contain\":true,\"selectedAttraction\":0.025,\"friction\":0.28}' id=\"su_image_carousel_6a577e1260dcd\"><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"999\" height=\"666\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-5.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-5.jpeg 999w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-5-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-5-768x512.jpeg 768w\" sizes=\"auto, (max-width: 999px) 100vw, 999px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"742\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-2.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-2.jpeg 990w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-2-300x225.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-2-768x576.jpeg 768w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"660\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-4.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-4.jpeg 990w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-4-300x200.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-4-768x512.jpeg 768w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"742\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-3.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-3.jpeg 990w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-3-300x225.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-3-768x576.jpeg 768w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/div><\/div><div class=\"su-image-carousel-item\"><div class=\"su-image-carousel-item-content\"><img loading=\"lazy\" decoding=\"async\" width=\"990\" height=\"742\" src=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-1.jpeg\" class=\"\" alt=\"\" srcset=\"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-1.jpeg 990w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-1-300x225.jpeg 300w, https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-content\/uploads\/sites\/28\/2024\/02\/Coesfo-1-768x576.jpeg 768w\" sizes=\"auto, (max-width: 990px) 100vw, 990px\" \/><\/div><\/div><\/div><script id=\"su_image_carousel_6a577e1260dcd_script\">if(window.SUImageCarousel){setTimeout(function() {window.SUImageCarousel.initGallery(document.getElementById(\"su_image_carousel_6a577e1260dcd\"))}, 0);}var su_image_carousel_6a577e1260dcd_script=document.getElementById(\"su_image_carousel_6a577e1260dcd_script\");if(su_image_carousel_6a577e1260dcd_script){su_image_carousel_6a577e1260dcd_script.parentNode.removeChild(su_image_carousel_6a577e1260dcd_script);}<\/script>\n","protected":false},"excerpt":{"rendered":"<p>Oaxaca de Ju\u00e1rez, Oax. 29 de febrero de 2024. Ante el incendio registrado en el municipio de San Lucas Quiavin\u00ed, se estableci\u00f3 un plan de combate a trav\u00e9s de personal t\u00e9cnico de la Comisi\u00f3n Estatal Forestal (Coesfo), la Comisi\u00f3n Nacional Forestal (Conafor) y personal de Protecci\u00f3n Civil de Tlacolula de Matamoros y de San Pablo [&hellip;]<\/p>\n","protected":false},"author":29,"featured_media":120948,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[8],"tags":[117],"class_list":["post-120942","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias","tag-coesfo"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-07-22 06:33:22","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/120942","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/users\/29"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/comments?post=120942"}],"version-history":[{"count":1,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/120942\/revisions"}],"predecessor-version":[{"id":120949,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/posts\/120942\/revisions\/120949"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media\/120948"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/media?parent=120942"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/categories?post=120942"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/comunicacion\/wp-json\/wp\/v2\/tags?post=120942"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}