{"id":28172,"date":"2020-07-27T10:32:24","date_gmt":"2020-07-27T15:32:24","guid":{"rendered":"https:\/\/www.oaxaca.gob.mx\/administracion\/?p=28172"},"modified":"2020-09-23T14:34:52","modified_gmt":"2020-09-23T19:34:52","slug":"personal-de-parques-publicos-se-capacita-en-prevencion-del-covid","status":"publish","type":"post","link":"https:\/\/www.oaxaca.gob.mx\/administracion\/personal-de-parques-publicos-se-capacita-en-prevencion-del-covid\/","title":{"rendered":"Personal de parques p\u00fablicos se capacita en prevenci\u00f3n del COVID"},"content":{"rendered":"<p>A trav\u00e9s del IMSS, decenas de trabajadores de Administraci\u00f3n se preparan para un sano regreso a los espacios p\u00fablicos en cuanto el sem\u00e1foro as\u00ed lo permita<\/p>\n<p>Oaxaca de Ju\u00e1rez, Oax., 27 de julio de 2020.- Personal de los parques y espacios p\u00fablicos bajo resguardo de la Secretar\u00eda de Administraci\u00f3n participan en cursos de capacitaci\u00f3n virtuales para conocer y aplicar buenas pr\u00e1cticas en la prevenci\u00f3n y reducci\u00f3n de infecciones de SARS-CoV-2. <\/p>\n<p>Desde casa, trabajadoras y trabajadores de la dependencia encabezada por Germ\u00e1n Espinosa Santib\u00e1\u00f1ez, aprovechan las herramientas tecnol\u00f3gicas para prepararse ante las nuevas normas de convivencia. <\/p>\n<p>A trav\u00e9s de la plataforma virtual del Instituto Mexicano del Seguro Social (IMSS) est\u00e1n capacit\u00e1ndose con la finalidad de ofrecer a los usuarios instalaciones y servicios con todas las medidas sanitarias cuando as\u00ed lo dicten las autoridades de los Servicios de Salud de Oaxaca. <\/p>\n<p>Responsables de parques, instructores, instructoras, personal de mantenimiento y administrativo participaron en los cursos \u201cRecomendaciones para un retorno seguro al trabajo ante COVID\u201d y \u201cTodo sobre la Prevenci\u00f3n del COVID\u201d, cuyo objetivo es contar con informaci\u00f3n que les ayude a minimizar los riesgos de contagio del virus, mediante la aplicaci\u00f3n de estrategias de buenas pr\u00e1cticas.<\/p>\n<p>Al respecto, el coordinador de Espacios P\u00fablicos Recreativos de la Secretar\u00eda de Administraci\u00f3n, Jos\u00e9 Gil S\u00e1nchez, destac\u00f3 que con esta capacitaci\u00f3n se atienden las indicaciones del gobernador Alejandro Murat Hinojosa para la adecuada y segura reincorporaci\u00f3n laboral y de servicios a la comunidad oaxaque\u00f1a.<\/p>\n<p>Precis\u00f3 que la instrucci\u00f3n del secretario de Administraci\u00f3n es establecer las estrategias de prevenci\u00f3n y control sanitario que, una vez que sea permitido por las autoridades del rubro, posibiliten la apertura y disfrute de los parques p\u00fablicos. <\/p>\n<p>Cabe se\u00f1alar que en esta preparaci\u00f3n constante se encuentran trabajadoras y trabajadores de los parques Ciudad de las Canteras, Del Agua Centenario, Oaxaca Bicentenario, Vinicio Castilla Soria, Luis Donaldo Colosio Murrieta, Bosque El Tequio, Polideportivo Venustiano Carranza, la Unidad Deportiva CAPCE, la Unidad Recreativa R\u00edo Atoyac y el Planetario Nundehui. -0-<\/p>\n<p>&#8212;<br \/>\nMaterial exclusivamente de car\u00e1cter informativo dirigido a medios de comunicaci\u00f3n, sin fines propagand\u00edsticos.<\/p>\n<p>Comunicado 770<\/p>\n<p>Personal de parques p\u00fablicos se capacita en prevenci\u00f3n del COVID<\/p>\n<p>* A trav\u00e9s del IMSS, decenas de trabajadores de Administraci\u00f3n se preparan para un sano regreso a los espacios p\u00fablicos en cuanto el sem\u00e1foro as\u00ed lo permita<\/p>\n<p>Oaxaca de Ju\u00e1rez, Oax., 27 de julio de 2020.- Personal de los parques y espacios p\u00fablicos bajo resguardo de la Secretar\u00eda de Administraci\u00f3n participan en cursos de capacitaci\u00f3n virtuales para conocer y aplicar buenas pr\u00e1cticas en la prevenci\u00f3n y reducci\u00f3n de infecciones de SARS-CoV-2. <\/p>\n<p>Desde casa, trabajadoras y trabajadores de la dependencia encabezada por Germ\u00e1n Espinosa Santib\u00e1\u00f1ez, aprovechan las herramientas tecnol\u00f3gicas para prepararse ante las nuevas normas de convivencia. <\/p>\n<p>A trav\u00e9s de la plataforma virtual del Instituto Mexicano del Seguro Social (IMSS) est\u00e1n capacit\u00e1ndose con la finalidad de ofrecer a los usuarios instalaciones y servicios con todas las medidas sanitarias cuando as\u00ed lo dicten las autoridades de los Servicios de Salud de Oaxaca. <\/p>\n<p>Responsables de parques, instructores, instructoras, personal de mantenimiento y administrativo participaron en los cursos \u201cRecomendaciones para un retorno seguro al trabajo ante COVID\u201d y \u201cTodo sobre la Prevenci\u00f3n del COVID\u201d, cuyo objetivo es contar con informaci\u00f3n que les ayude a minimizar los riesgos de contagio del virus, mediante la aplicaci\u00f3n de estrategias de buenas pr\u00e1cticas.<\/p>\n<p>Al respecto, el coordinador de Espacios P\u00fablicos Recreativos de la Secretar\u00eda de Administraci\u00f3n, Jos\u00e9 Gil S\u00e1nchez, destac\u00f3 que con esta capacitaci\u00f3n se atienden las indicaciones del gobernador Alejandro Murat Hinojosa para la adecuada y segura reincorporaci\u00f3n laboral y de servicios a la comunidad oaxaque\u00f1a.<\/p>\n<p>Precis\u00f3 que la instrucci\u00f3n del secretario de Administraci\u00f3n es establecer las estrategias de prevenci\u00f3n y control sanitario que, una vez que sea permitido por las autoridades del rubro, posibiliten la apertura y disfrute de los parques p\u00fablicos. <\/p>\n<p>Cabe se\u00f1alar que en esta preparaci\u00f3n constante se encuentran trabajadoras y trabajadores de los parques Ciudad de las Canteras, Del Agua Centenario, Oaxaca Bicentenario, Vinicio Castilla Soria, Luis Donaldo Colosio Murrieta, Bosque El Tequio, Polideportivo Venustiano Carranza, la Unidad Deportiva CAPCE, la Unidad Recreativa R\u00edo Atoyac y el Planetario Nundehui. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>A trav\u00e9s del IMSS, decenas de trabajadores de Administraci\u00f3n se preparan para un sano regreso a los espacios p\u00fablicos en cuanto el sem\u00e1foro as\u00ed lo permita Oaxaca de Ju\u00e1rez, Oax., 27 de julio de 2020.- Personal de los parques y espacios p\u00fablicos bajo resguardo de la Secretar\u00eda de Administraci\u00f3n participan en cursos de capacitaci\u00f3n virtuales [&hellip;]<\/p>\n","protected":false},"author":72,"featured_media":28173,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"episode_type":"","audio_file":"","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"","filesize_raw":"","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":"","footnotes":""},"categories":[12],"tags":[],"class_list":["post-28172","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"acf":[],"publishpress_future_action":{"enabled":false,"date":"2026-05-20 16:21:04","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/www.oaxaca.gob.mx\/administracion\/wp-json\/wp\/v2\/posts\/28172","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.oaxaca.gob.mx\/administracion\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.oaxaca.gob.mx\/administracion\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/administracion\/wp-json\/wp\/v2\/users\/72"}],"replies":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/administracion\/wp-json\/wp\/v2\/comments?post=28172"}],"version-history":[{"count":0,"href":"https:\/\/www.oaxaca.gob.mx\/administracion\/wp-json\/wp\/v2\/posts\/28172\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/administracion\/wp-json\/wp\/v2\/media\/28173"}],"wp:attachment":[{"href":"https:\/\/www.oaxaca.gob.mx\/administracion\/wp-json\/wp\/v2\/media?parent=28172"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/administracion\/wp-json\/wp\/v2\/categories?post=28172"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.oaxaca.gob.mx\/administracion\/wp-json\/wp\/v2\/tags?post=28172"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}